{"id":7482,"date":"2021-04-01T12:48:41","date_gmt":"2021-04-01T12:48:41","guid":{"rendered":"https:\/\/odysseyshowcase.org\/\/?page_id=7482"},"modified":"2021-04-02T11:13:05","modified_gmt":"2021-04-02T11:13:05","slug":"en-resume","status":"publish","type":"page","link":"https:\/\/odysseyshowcase.org\/fr\/a-propos-de-nous\/en-resume\/","title":{"rendered":"En r\u00e9sum\u00e9"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"7482\" class=\"elementor elementor-7482\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f76a82 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle elementor-invisible\" data-id=\"0f76a82\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;bounce&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16f0e23\" data-id=\"16f0e23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba12f3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba12f3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5dcade0\" data-id=\"5dcade0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4a7fc6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d4a7fc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avis sur Odyssey Showcase<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1dbcad elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e1dbcad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;2.5&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpolyline points=&#039;0,18 12,6 24,18 &#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80d2bfb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"80d2bfb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e70dafb\" data-id=\"e70dafb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc36353 elementor-widget elementor-widget-text-editor\" data-id=\"fc36353\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Le don du jazz, le don de la culture, le don de la musique et le don d&#8217;une exp\u00e9rience live, partag\u00e9e par tous les \u00e2ges. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5158d69 elementor-widget elementor-widget-toggle\" data-id=\"5158d69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8521\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8521\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8521\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8521\"><div class=\"wp-block-column\"><p class=\"has-black-color has-text-color\">Le don du jazz, le don de la culture, le don de la musique et le don d&#8217;une exp\u00e9rience live, partag\u00e9e par tous les \u00e2ges.<br \/>J&#8217;ai rencontr\u00e9 Deborah Davis, sa distribution et l&#8217;\u00e9quipe de l&#8217;Odyssey Showcase en 2014, et j&#8217;ai \u00e9t\u00e9 imm\u00e9diatement intrigu\u00e9e et inspir\u00e9e. J&#8217;ai \u00e9t\u00e9 \u00e9poustoufl\u00e9 par tant de personnes diverses rassembl\u00e9es pour faire vivre notre histoire, notre histoire. Cela m&#8217;a montr\u00e9 la passion de notre jeunesse et la force de nos a\u00een\u00e9s. Se sentir, comme une communaut\u00e9 de conteurs. L&#8217;histoire originale autour du feu du soir. Odyssey Showcase apporte la communaut\u00e9 et le feu \u00e0 travers la musique, la danse et le th\u00e9\u00e2tre. Je suis honor\u00e9 de faire partie de cette famille.<br \/>Brad Denys<\/p><p>\u00c0 propos de Brad: En plus de nombreuses tourn\u00e9es \u00e0 travers l&#8217;Europe, l&#8217;Asie, l&#8217;Am\u00e9rique du Sud et l&#8217;Australie, y compris entre autres t\u00e2ches, se produisant dans plus de 1600 spectacles avec le Cirque du Soleil, Brad travaille avec Deborah Davis en tant qu&#8217;interpr\u00e8te et consultante depuis 2014 avec \u00ab Le Canada rugit: un avant-go\u00fbt musical de notre patrimoine canadien ,Le Canada parle \u00bbet\u00ab Le don du jazz .<br \/>Brad Denys<\/p><\/div><div class=\"wp-block-column\">\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ee07388\" data-id=\"ee07388\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21df7b3 elementor-widget elementor-widget-text-editor\" data-id=\"21df7b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Avec la chanson, la danse et les contes, les publics de tous \u00e2ges et en particulier les \u00e9tudiants ont \u00e9t\u00e9 guid\u00e9s \u00e0 travers l&#8217;importance de l&#8217;histoire et de la culture du Canada, partag\u00e9e par tous les \u00e2ges. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bff5be elementor-widget elementor-widget-toggle\" data-id=\"3bff5be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6291\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6291\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6291\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6291\"><div class=\"wp-block-column\"><p class=\"has-black-color has-text-color\">Au cours des 14 derni\u00e8res ann\u00e9es, j&#8217;ai eu le plaisir de faire partie des productions d&#8217;Odyssey Showcase. J&#8217;ai le sentiment sinc\u00e8re que leurs productions sont des ic\u00f4nes d&#8217;une valeur \u00e9ducative et de divertissement inestimable.<\/p><p>Je m&#8217;appelle Darin Kyle. Je suis le premier champion du monde canadien de claquettes. Je suis un conf\u00e9rencier d&#8217;honneur et un activiste local du \u00abd\u00e9veloppement communautaire\u00bb \u00e0 Ottawa. Mes racines dans cette ville sont profondes. Et j&#8217;ai un profond respect pour la fa\u00e7on dont Deborah Davis, son \u00e9quipe et ses acteurs ont eu un impact sur la vie des \u00e9tudiants. Avec la chanson, la danse et les contes, les publics de tous \u00e2ges et en particulier les \u00e9tudiants ont \u00e9t\u00e9 guid\u00e9s par l\u2019importance de l\u2019histoire et de la culture du Canada.<\/p><p>Odyssey Showcase se consacre \u00e0 trouver les bons talents pour faire le travail et le fait extraordinairement bien. Je suis d&#8217;avis que si on lui donne la possibilit\u00e9 d&#8217;appuyer le projet Canada Speaks, alors la seule ligne de conduite consiste \u00e0 apporter tout votre soutien \u00e0 l&#8217;initiative et \u00e0 surfer sur la vague de succ\u00e8s qui s&#8217;ensuivra. Par exp\u00e9rience, ce sera un partenariat fond\u00e9 sur un succ\u00e8s mutuellement assur\u00e9. Je vous invite \u00e0 vivre ce partenariat par vous-m\u00eame.\u00a0<\/p><p>Darin David Kyle<\/p><p>Darin Kyle<\/p><\/div><div class=\"wp-block-column\">\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd80b1d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fd80b1d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-80a67f2\" data-id=\"80a67f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcf2370 elementor-widget elementor-widget-text-editor\" data-id=\"fcf2370\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Surtout, Deborah est l&#8217;une de ces rares personnes qui englobe un talent musical avec un sens profond du but. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7208b9 elementor-widget elementor-widget-toggle\" data-id=\"b7208b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1921\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1921\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1921\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1921\"><div class=\"wp-block-column\"><p class=\"has-black-color has-text-color\">Deborah Davis est une personne que les gens respectent et admirent avec beaucoup d&#8217;affection. En partie \u00e0 cause de l&#8217;\u00e9nergie incroyable qu&#8217;elle est pr\u00eate \u00e0 consacrer \u00e0 ce en quoi elle croit, mais plus encore, c&#8217;est parce que c&#8217;est ce qu&#8217;elle ressent pour chacun d&#8217;eux. Les acteurs et l&#8217;\u00e9quipe, les sponsors, les enseignants, les enfants, les \u00e9tudiants et tous ceux associ\u00e9s \u00e0 tout ce que Deborah touche tous la soutiennent parce qu&#8217;elle donne vie d&#8217;une mani\u00e8re dont les autres ne peuvent que r\u00eaver, tant de choses sont \u00e9mouvantes, belles, inspirantes et, tout simplement, les meilleures en nous. Deborah rassemble les gens \u00e0 travers les arts.<br \/>\u00ab\u2026 Surtout, Deborah est l&#8217;une de ces rares personnes qui englobe un talent musical avec un sens profond du but. Sa ferme conviction de soutenir la culture canadienne lui a donn\u00e9 une \u00abraison d\u2019\u00eatre\u00bb. Mon association en tant que directrice musicale pour ses nombreux efforts a \u00e9t\u00e9 un grand voyage qui remonte \u00e0 vingt ans, y compris des projets tels que Un go\u00fbt musical de notre patrimoine canadien, Satin Dolls, What is this Thing called Jazz, Choonga Changa et divers autres spectacles musicaux.<br \/>Je m&#8217;en voudrais de ne pas mentionner sa g\u00e9n\u00e9rosit\u00e9 de faire ressortir et de payer personnellement des centaines d&#8217;enfants \u00e9conomiquement d\u00e9favoris\u00e9s au cours des dix-neuf derni\u00e8res ann\u00e9es pour avoir l&#8217;opportunit\u00e9 de voir les productions \u2026\u2026 Deborah est tr\u00e8s m\u00e9ritante et attendue depuis longtemps pour tout prix en les arts. &#8220;<br \/>Peter Beaudoin, directeur musical et musicien<br \/>\u00c0 propos de Peter: Peter a plus de trente ans d&#8217;exp\u00e9rience en tant que musicien, batteur et chef de groupe. Il a \u00e9galement effectu\u00e9 neuf tourn\u00e9es mondiales de spectacles des Forces canadiennes en Bosnie, en Afghanistan et \u00e0 Duba\u00ef. Il a eu une carri\u00e8re impressionnante en tant qu&#8217;interpr\u00e8te et musicien d&#8217;enregistrement respect\u00e9 et tr\u00e8s recherch\u00e9 avec de nombreux artistes canadiens et internationaux de classe mondiale, dont Harry Chapin, Petula Clark, Rita Coolidge et Rob McConnell (Boss Brass) pour n&#8217;en nommer que quelques-uns. Peter travaille avec Deborah Davis depuis 1997 sur un certain nombre de projets en tant que directeur musical, notamment Satin Dolls, What is this Thing Called Jazz, Canada Roars et le Canadian Musical Odyssey Ensemble.<\/p><p>Peter Beaudoin<\/p><\/div><div class=\"wp-block-column\">\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17e866b\" data-id=\"17e866b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac7fa01 elementor-widget elementor-widget-text-editor\" data-id=\"ac7fa01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> The Gift of Jazz est une exp\u00e9rience qui capture parfaitement le voyage \u00e9clectique de l&#8217;\u00e9volution musicale nord-am\u00e9ricaine. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c27dd8 elementor-widget elementor-widget-toggle\" data-id=\"7c27dd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1301\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1301\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1301\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1301\"><div class=\"wp-block-column\"><p class=\"has-black-color has-text-color\">The Gift of Jazz est une exp\u00e9rience qui capture parfaitement le voyage \u00e9clectique de l&#8217;\u00e9volution musicale nord-am\u00e9ricaine. L&#8217;\u00e9quipe diversifi\u00e9e est compos\u00e9e de professionnels d\u00e9di\u00e9s \u00e0 diffuser l&#8217;immense beaut\u00e9 et la joie que le jazz offre \u00e0 l&#8217;esprit! C&#8217;est un privil\u00e8ge de cr\u00e9er avec cette production, et je pr\u00e9vois \u00e0 chaque \u00e9tape que nous aurons l&#8217;opportunit\u00e9 de partager l&#8217;histoire et l&#8217;\u00e9merveillement du jazz.<br \/>Jamall Jackson Rogers (juste Jamaal)<br \/>Lien YouTube Just Jamaal<br \/>\u00c0 propos de Jamaal: Jamaal Jackson Rogers est un po\u00e8te prim\u00e9, des artistes hip-hop, un \u00e9ducateur artistique et un entrepreneur cr\u00e9atif. Il est actuellement po\u00e8te laur\u00e9at anglais d\u2019Ottawa et a fait conna\u00eetre son travail \u00e0 un public national et \u00e9tranger. Ses moments marquants sont lorsqu&#8217;il \u00e9tablit des liens intimes avec ses participants lors de ses performances et \u00e9changes d&#8217;ateliers.<\/p><p>Ses sujets vont de la maturit\u00e9 \u00e9motionnelle \u00e0 la justice sociale, des luttes de la vie quotidienne \u00e0 la condition humaine. Il est p\u00e8re de cinq enfants et r\u00e9side \u00e0 Ottawa, au Canada, utilisant la capitale nationale et son studio de performance, THE ORIGIN ARTS &amp; amp; CENTRE COMMUNAUTAIRE, comme tremplin pour pratiquer, enseigner, encadrer et d\u00e9fendre les arts.<br \/>Jamaal Jackson Rogers<\/p><\/div><div class=\"wp-block-column\">\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d563914 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d563914\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-751c83c\" data-id=\"751c83c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc5e4af elementor-widget elementor-widget-text-editor\" data-id=\"dc5e4af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Odyssey pr\u00e9sente la Saint-Valentin ultime au jazz <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0426ad elementor-widget elementor-widget-toggle\" data-id=\"c0426ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2011\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2011\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2011\"><div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> La musique jazz a certainement cr\u00e9\u00e9 suffisamment de standards romantiques pour se glisser dans la cr\u00e9ation d&#8217;une liste de lecture pour la Saint-Valentin pour ce d\u00eener aux chandelles avec votre bien-aim\u00e9. Ella et Louis chantant &#8220;Cheek to Cheek&#8221;, Miles apaisant corne sur &#8220;Stella by Starlight&#8221;, le chant sensuel du chant des f\u00eates &#8220;Let&#8217;s Do It (Let&#8217;s Fall In Love)&#8221; et, bien s\u00fbr, le triste Chet et son dr\u00f4le de Valentine. \/ p>\nLire la suite\n\nTerre \u00e0 Andr\u00e9\n\n<\/div>\n<div class = \"wp-block-column\"> <\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a346d97\" data-id=\"a346d97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ada98b elementor-widget elementor-widget-text-editor\" data-id=\"3ada98b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Il est toujours merveilleux d&#8217;assister \u00e0 un hommage \u00e0 une forme d&#8217;art am\u00e9ricaine, car cela met un chapeau sur toute la diversit\u00e9 qui contribue \u00e0 sa cr\u00e9ation. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccf0f0a elementor-widget elementor-widget-toggle\" data-id=\"ccf0f0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2141\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2141\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2141\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2141\"><div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> Il est toujours merveilleux d&#8217;assister \u00e0 un hommage \u00e0 une forme d&#8217;art am\u00e9ricaine, car cela met un chapeau sur toute la diversit\u00e9 qui contribue \u00e0 sa cr\u00e9ation. L&#8217;exp\u00e9rience am\u00e9ricaine, dans son essence m\u00eame, t\u00e9moigne de l&#8217;implication de tant de cultures et d&#8217;horizons et des b\u00e9n\u00e9dictions qui en \u00e9mergent. <\/p>\nLe jazz est un tr\u00e9sor am\u00e9ricain, un cadeau offert par ses habitants au monde, repr\u00e9sentant musicalement et rythmiquement sa douleur, sa joie, son \u00e9nergie, sa jeunesse, son insouciance et son \u00e9merveillement. Cela se voit clairement dans la pr\u00e9sentation de Gift of Jazz de Deborah Davis, qui raconte la naissance, la r\u00e9surrection et le d\u00e9ploiement de cette forme d\u2019art sur la sc\u00e8ne mondiale.\nAu c\u0153ur de cette performance, nous voyons et ressentons l&#8217;\u00e2me de la diaspora africaine. Nous entendons l&#8217;agonie du passage du milieu et l&#8217;espoir d&#8217;un peuple nouvellement lib\u00e9r\u00e9 de l&#8217;esclavage. Alors que le paysage et le si\u00e8cle tournent et que l&#8217;Am\u00e9rique commence \u00e0 fl\u00e9chir, nous assistons aux influences des classiques europ\u00e9ens et de la modernit\u00e9 sur la pr\u00e9sentation du jazz dans le courant dominant de la culture. La pr\u00e9sentation \u00abGift\u00bb rend hommage aux grands interpr\u00e8tes de Bessie Smith, Louis \u2018Satchmo\u2019 Armstrong, Fats Waller et bien d\u2019autres.\n\nTous les interpr\u00e8tes et musiciens de \u00abGift\u00bb sont des artisans d\u00e9vou\u00e9s et des amoureux des arts et leur professionnalisme est \u00e9vident dans cette performance.\n\nIl est tr\u00e8s clair que Deborah Davis et Segue to Jazz ont une gagnante dans le \u00abDon du jazz\u00bb alors qu\u2019elle continue de partager cette exp\u00e9rience avec la communaut\u00e9 du Grand Ottawa. Lorsqu&#8217;il est pr\u00e9sent\u00e9 \u00e0 nouveau, il est \u00e0 voir absolument.\n\nMichael Curtis Hanna\n\u00c0 propos de Michael: Michael a eu la chance de vivre l&#8217;exp\u00e9rience de vie unique dans une communaut\u00e9 avec Sarah Vaughn, Al Hibler, Thad Jones, Nat Adderly et une foule de musiciens renomm\u00e9s au coin de la rue de chez lui. N\u00e9 \u00e0 Detroit, Michigan et \u00e9lev\u00e9 \u00e0 Teaneck, New Jersey, il a \u00e9t\u00e9 plong\u00e9 dans une grande partie du paysage musical changeant des 50 derni\u00e8res ann\u00e9es.\n\u00c0 la recherche de J\u00e9sus et de la musique gospel Michael a chant\u00e9 dans des chorales d&#8217;\u00e9glises de Detroit \u00e0 Ottawa. En tant que chanteur solo, Michael a tourn\u00e9 avec et pour son p\u00e8re, feu Sir Roland Hanna aux \u00c9tats-Unis et au Japon. Ayant un penchant pour l\u2019harmonie vocale masculine, Michael a nourri cet amour du chant avec des groupes masculins a cappella, dont le Canadian Men\u2019s Chorus de Toronto.\n\nMichael dirige actuellement Rahanna Music Inc. et a d\u00e9velopp\u00e9 plus de 300 compositions de Sir Roland Hanna. On le retrouve \u00e9galement sur plusieurs CD en plus de se produire \u00e0 Ottawa et \u00e0 l\u2019\u00e9tranger.\n\nMichael Curtis Hanna\n\n<\/div>\n<div class = \"wp-block-column\"> <\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-945f9df elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"945f9df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b370e50\" data-id=\"b370e50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19aa1c7 elementor-widget elementor-widget-text-editor\" data-id=\"19aa1c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> En tant qu\u2019am\u00e9ricain vivant au Canada, j\u2019ai \u00e9t\u00e9 surpris d\u2019apprendre \u00e0 quel point l\u2019histoire musicale du Canada a ajout\u00e9 et chang\u00e9 le monde. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bb733c elementor-widget elementor-widget-toggle\" data-id=\"4bb733c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7931\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7931\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7931\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7931\"><p>J&#8217;ai assist\u00e9 \u00e0 cette performance et j&#8217;ai \u00e9t\u00e9 compl\u00e8tement et totalement transperc\u00e9 par le talent, la chor\u00e9graphie, le contenu et les informations du spectacle le plus agr\u00e9able que j&#8217;ai vu depuis de nombreuses ann\u00e9es. En tant qu\u2019am\u00e9ricain vivant au Canada, j\u2019ai \u00e9t\u00e9 surpris d\u2019apprendre \u00e0 quel point l\u2019histoire musicale du Canada a ajout\u00e9 et chang\u00e9 le monde. Les \u00e9coliers qui fr\u00e9quentaient \u00e9taient captiv\u00e9s et attentifs et \u00e9taient une joie de les regarder agiter leurs bras et chanter. Je recommande vivement ce spectacle \u00e0 tous ceux qui aiment la musique! Deborah Davis \u00e9tait une pure joie et son talent transcende de nombreuses \u00e9poques musicales. Bravo \u00e0 un tr\u00e8s grand spectacle!<\/p><p>Alicia Bailey<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3876e0d\" data-id=\"3876e0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf8a317 elementor-widget elementor-widget-text-editor\" data-id=\"cf8a317\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> L&#8217;\u00e9quipe s&#8217;est consult\u00e9e moi-m\u00eame et les autres ambassadeurs culturels des Premi\u00e8res Nations pour s&#8217;assurer que la culture, les gens et l&#8217;histoire sont pr\u00e9sent\u00e9s de mani\u00e8re appropri\u00e9e. Ces \u00e9tapes sont tr\u00e8s appr\u00e9ci\u00e9es et ont donc renforc\u00e9 notre participation \u00e0 l&#8217;Odyss\u00e9e musicale. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15fb49c elementor-widget elementor-widget-toggle\" data-id=\"15fb49c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2301\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2301\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2301\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2301\"><p>Je m&#8217;appelle Jason Gullo Mullins de la nation Cherokee. Je suis un ambassadeur culturel des Premi\u00e8res Nations, un \u00e9ducateur, un excellent artiste et un artiste de la sc\u00e8ne. Mon r\u00f4le d&#8217;ambassadeur culturel est d&#8217;\u00e9duquer et de repr\u00e9senter correctement les Premi\u00e8res Nations.<\/p><p>Je joue avec l\u2019Odyssey Showcase et l\u2019ensemble Canadian Musical Odyssey depuis 12 ans. Au cours de cette p\u00e9riode, nous avons \u00e9t\u00e9 accueillis \u00e0 bras chaleureux dans le casting en tant que famille. L&#8217;\u00e9quipe s&#8217;est consult\u00e9e moi-m\u00eame et les autres ambassadeurs culturels des Premi\u00e8res Nations pour s&#8217;assurer que la culture, les gens et l&#8217;histoire sont pr\u00e9sent\u00e9s de mani\u00e8re appropri\u00e9e. Ces \u00e9tapes sont tr\u00e8s appr\u00e9ci\u00e9es et ont donc renforc\u00e9 notre participation \u00e0 l&#8217;Odyss\u00e9e musicale.<\/p><p>Canada Roars et Canada Speaks sont une superbe mise en page de l&#8217;histoire du Canada, le format de l&#8217;enseignement par les arts permet aux jeunes d&#8217;apprendre plus facilement, surtout lorsque vous les divertissez et les engagez avec des m\u00e9diums auxquels ils peuvent tous s&#8217;identifier: musique live, danse, chant et th\u00e9\u00e2tre. .<\/p><p>J&#8217;ai h\u00e2te de jouer \u00e0 nouveau avec la distribution bient\u00f4t. &#8220;<\/p><p>Jason.G. Mullins<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee147ca elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ee147ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-97c773e\" data-id=\"97c773e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95b45bd elementor-widget elementor-widget-text-editor\" data-id=\"95b45bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> une merveilleuse occasion de d\u00e9montrer les nombreuses contributions positives que les Premiers Peuples ont apport\u00e9es ici m\u00eame sur notre territoire traditionnel d&#8217;Odawa, \u00e9galement connu sous le nom d&#8217;Ottawa <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a899b15 elementor-widget elementor-widget-toggle\" data-id=\"a899b15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1761\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1761\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1761\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1761\"><div class=\"wp-block-column\"><p class=\"has-black-color has-text-color\">Travailler avec Odyssey Showcase sur Canada Roars et Canada Speaks a \u00e9t\u00e9 une exp\u00e9rience tellement riche, non seulement pour moi, mais aussi pour les \u00e9tudiants. Je fais partie de la m\u00eame culture que le personnage que je repr\u00e9sente; Hiawatha, donc je ressens une connexion si profonde avec lui et cela se ressent pour le public, quel que soit son \u00e2ge, car tout le monde est toujours d\u00e9sireux d&#8217;en savoir plus et surpris quand ils apprennent quelque chose de nouveau. Un \u00e9l\u00e8ve de la Premi\u00e8re nation Mohawk qui a particip\u00e9 \u00e0 Canada Speaks \u00e9tait enthousiasm\u00e9 parce qu&#8217;il a pu partager une partie de son histoire avec ses camarades de classe. Il pensait que c&#8217;\u00e9tait \u00abvraiment cool\u00bb que je sois Mohawk et que je d\u00e9peigne une figure importante qu&#8217;il connaissait et \u00e0 laquelle il pouvait s&#8217;identifier\u00a0<br \/>\u00catre en mesure de mettre en valeur cette figure importante d&#8217;une mani\u00e8re exempte de st\u00e9r\u00e9otypes et d&#8217;hypoth\u00e8ses est exactement ce dont les jeunes du Canada ont besoin. Canada Speaks est la plateforme id\u00e9ale pour cela.<br \/>Will Lafrance<\/p><\/div><div class=\"wp-block-column\">\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1a2d3e4\" data-id=\"1a2d3e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9659724 elementor-widget elementor-widget-text-editor\" data-id=\"9659724\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Vous pouvez voir le changement inspir\u00e9 par l&#8217;\u00e9ducation \u00e0 travers les arts, l&#8217;\u00e9vidence est dans leurs yeux et dans leurs sourires! <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95680c3 elementor-widget elementor-widget-toggle\" data-id=\"95680c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1561\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1561\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1561\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1561\"><p>Lorsque je d\u00e9cris le r\u00f4le de Pauline Johnson, c&#8217;est toujours une b\u00e9n\u00e9diction de voir les esprits et les curiosit\u00e9s des jeunes s&#8217;ouvrir lorsqu&#8217;ils d\u00e9couvrent certains des tr\u00e9sors cach\u00e9s de l&#8217;histoire canadienne. De nombreux participants arrivent sans savoir qui sont les personnages, mais quand ils Vous pouvez voir le changement inspir\u00e9 par l&#8217;\u00e9ducation \u00e0 travers les arts, la preuve est dans leurs yeux et dans leurs sourires<\/p><p>Rhonda Doxtator<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-381be2b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"381be2b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bf60813\" data-id=\"bf60813\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3846b77 elementor-widget elementor-widget-text-editor\" data-id=\"3846b77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Les pi\u00e8ces de th\u00e9\u00e2tre se concentrent sur la fa\u00e7on dont les Premi\u00e8res Nations ont influenc\u00e9 notre histoire, s&#8217;harmonisent parfaitement avec le nouvel accent mis sur les questions autochtones \u00e0 l&#8217;\u00e9cole et dans la soci\u00e9t\u00e9 canadienne en g\u00e9n\u00e9ral. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dfdf7b elementor-widget elementor-widget-toggle\" data-id=\"5dfdf7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9851\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9851\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9851\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9851\"><p>Je suis attrist\u00e9 de lire que la production Canada Roars Spring n&#8217;aura pas lieu cette ann\u00e9e. Ce programme sur l\u2019histoire du Canada a offert aux \u00e9tudiants un r\u00e9sum\u00e9 tr\u00e8s unique et inspirant du pass\u00e9 du Canada. Raconter l&#8217;histoire avec des acteurs, de la danse et de la musique a insuffl\u00e9 un sentiment de fiert\u00e9 dans l&#8217;\u00e9dification de notre nation. Le contenu couvrait tr\u00e8s bien le programme des 7e et 8e ann\u00e9es et a motiv\u00e9 les \u00e9l\u00e8ves \u00e0 travailler dur dans l&#8217;unit\u00e9 d&#8217;histoire dans l&#8217;espoir de gagner le privil\u00e8ge d&#8217;assister \u00e0 la production. Les pi\u00e8ces se concentrent sur la fa\u00e7on dont les Premi\u00e8res Nations ont influenc\u00e9 notre histoire, s&#8217;harmonisent parfaitement avec le nouvel accent mis sur les questions autochtones \u00e0 l&#8217;\u00e9cole et dans la soci\u00e9t\u00e9 canadienne en g\u00e9n\u00e9ral.<\/p><p>J&#8217;esp\u00e8re que des plans pourront \u00eatre faits pour que le spectacle soit pr\u00e9sent\u00e9 dans un proche avenir. En un peu plus de 2 heures, le spectacle a fait revivre l&#8217;histoire de mes \u00e9l\u00e8ves, ce que le manuel et les vid\u00e9os \u00e9taient rarement capables de faire en 10 semaines de cours!<\/p><p>Paul Graham, Glashan Public School \/ 8e ann\u00e9e<br \/>\u00c9cole publique de Glashan \/ 8e ann\u00e9e<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bb2f99b\" data-id=\"bb2f99b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d840547 elementor-widget elementor-widget-text-editor\" data-id=\"d840547\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Nous ne pouvons sous-estimer l&#8217;importance des arts dans la vie de nos \u00e9l\u00e8ves. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f0c443 elementor-widget elementor-widget-toggle\" data-id=\"7f0c443\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1331\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1331\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1331\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1331\"><p>Je suis enseignant \u00e0 la Connaught Public School et j&#8217;enseigne \u00e0 un groupe d&#8217;\u00e9l\u00e8ves ayant un retard de d\u00e9veloppement dans un milieu semi-int\u00e9gr\u00e9.<br \/>Nous avons \u00e9t\u00e9 extr\u00eamement chanceux d&#8217;avoir pu participer au salon Canada Roars. C&#8217;est une fa\u00e7on unique de raconter l&#8217;histoire du Canada. Cela a vraiment donn\u00e9 vie \u00e0 l&#8217;histoire de mes \u00e9tudiants.<br \/>Non seulement ils ont pu voir la progression de la musique, mais ils ont \u00e9galement rencontr\u00e9 les interpr\u00e8tes qui sont rest\u00e9s en costume et en personnage pour que leurs enfants puissent interagir avec eux \u00e0 titre personnel, participer \u00e0 la musique et \u00e0 la danse, poser des questions, d\u00e9couvrez la culture et les artefacts d&#8217;hier. Les artistes \u00e9taient gentils et patients et tr\u00e8s enthousiastes \u00e0 l&#8217;id\u00e9e de partager leurs connaissances et leurs comp\u00e9tences.<br \/>Ce programme est important car il montre aux \u00e9tudiants de tous horizons l&#8217;histoire du Canada, sa musique et sa culture. Nous ne pouvons sous-estimer l&#8217;importance des arts dans la vie de nos \u00e9tudiants. Cela nous donne du sens et de la profondeur et une plus grande appr\u00e9ciation et implication dans notre histoire \u00e0 mesure qu&#8217;elle prend vie.<br \/>Merci d\u2019avoir financ\u00e9 ce programme et j\u2019estime qu\u2019il doit se poursuivre \u00e0 l\u2019avenir afin que, ann\u00e9e apr\u00e8s ann\u00e9e, les \u00e9tudiants puissent vivre l\u2019\u00e9merveillement de l\u2019histoire de la musique et de la danse au Canada.<\/p><p>Anne-Marie de Souza<br \/>\u00c9cole publique Connaught<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a88db9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2a88db9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-149925e\" data-id=\"149925e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f27cc0 elementor-widget elementor-widget-text-editor\" data-id=\"3f27cc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> En tant qu&#8217;enseignant de 6e ann\u00e9e, je consid\u00e8re The Gift of Jazz &#8220;comme un&#8221; cadeau &#8220;\u00e9ducatif pour tous les \u00e9l\u00e8ves de niveau junior-senior <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fb1d96 elementor-widget elementor-widget-toggle\" data-id=\"9fb1d96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1671\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1671\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1671\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1671\"><p>\u00a0Invit\u00e9s Mes invit\u00e9s et moi avons appr\u00e9ci\u00e9 chaque chanson, les chanteurs, les danseurs, les acteurs et les discours qui encadraient et contextualisaient les chansons. . . . les toiles de fond et les diapositives, le groupe, l&#8217;\u00e9clairage, la chor\u00e9graphie, les niveaux sonores &#8211; tout est fabuleux! Un spectacle formidable. . . . . il doit \u00eatre r\u00e9p\u00e9t\u00e9 chaque ann\u00e9e et plus d&#8217;un soir. . . avec des \u00e9tudiants invit\u00e9s de chaque lyc\u00e9e de la ville, pour apprendre quelque chose sur la musique et l&#8217;histoire des Noirs.\u00a0<\/p><p>Floralove Katz<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-718337a\" data-id=\"718337a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e731b0 elementor-widget elementor-widget-text-editor\" data-id=\"6e731b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> La musique vivante, le groupe impeccable et les interpr\u00e8tes ont diverti le public tout au long. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e7c600 elementor-widget elementor-widget-toggle\" data-id=\"1e7c600\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3191\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3191\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3191\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3191\"><div class=\"wp-block-column\"><p class=\"has-black-color has-text-color\">C&#8217;est notre deuxi\u00e8me ann\u00e9e d&#8217;assister aux performances de Deborah Davis et Odyssey Showcase, et nous avons ador\u00e9 chaque minute. La musique vivante, le groupe impeccable et les interpr\u00e8tes ont diverti le public tout au long. Cette ann\u00e9e, Gift of Jazz a pr\u00e9sent\u00e9 une merveilleuse s\u00e9lection de chansons incroyables des plus grands chanteurs de jazz du si\u00e8cle dernier\u2026 .Deborah, Stefan Keyes, Michael C. Hanna et le danseur de claquettes Darin Kyle ont gard\u00e9 le niveau d&#8217;\u00e9nergie \u00e9lev\u00e9, avec le public rebondissant \u00e0 le rythme de leurs chansons tout au long. Il n&#8217;y a pas eu d&#8217;accalmie dans la performance du d\u00e9but \u00e0 la fin. La qualit\u00e9 de la musique, de la danse et du chant \u00e9tait une source d&#8217;inspiration.\u00a0<\/p><p>Anna Rubinstein<\/p><\/div><div class=\"wp-block-column\">\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-479f59a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"479f59a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-33751a7\" data-id=\"33751a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b49fcd8 elementor-widget elementor-widget-text-editor\" data-id=\"b49fcd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Spectacle spectaculaire! <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c943e29 elementor-widget elementor-widget-toggle\" data-id=\"c943e29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2111\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2111\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2111\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2111\"><div class=\"wp-block-column\"><p class=\"has-black-color has-text-color\">Spectacle spectaculaire! Nous avons eu droit \u00e0 une soir\u00e9e absolument \u00e9poustouflante &#8211; \u00e0 la fois visuellement et musicalement, des costumes d&#8217;\u00e9poque aux voix \u00e9tonnantes, fortes et puissantes de Deborah, Michael et Stefan !!! \u2026 .De l&#8217;Afrique \u00e0 nos jours\u2026 .une histoire bien racont\u00e9e \u00e0 travers la musique. F\u00e9licitations \u00e0 la TD et \u00e0 tous les membres de The Gift of Jazz.\u00a0<\/p><p>Marques Raffi<\/p><\/div><div class=\"wp-block-column\">\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c49f5f7\" data-id=\"c49f5f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71fa64f elementor-widget elementor-widget-text-editor\" data-id=\"71fa64f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> C&#8217;\u00e9tait amusant, \u00e9motionnel, professionnel et patriotique <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-558475c elementor-widget elementor-widget-toggle\" data-id=\"558475c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8961\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8961\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8961\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8961\"><div class=\"wp-block-column\"><p class=\"has-black-color has-text-color\">J&#8217;ai \u00e9t\u00e9 submerg\u00e9 par la repr\u00e9sentation de A Musical Taste of Our Canadian Heritage. C&#8217;\u00e9tait amusant, \u00e9motionnel, professionnel et patriotique. Je le recommande vivement aux Canadiens de tout \u00e2ge. Bravo Deborah Davis!\u00a0<\/p><p>Jim Watson<\/p><\/div><div class=\"wp-block-column\">\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b3e3c4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7b3e3c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3249e0c\" data-id=\"3249e0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fed52a elementor-widget elementor-widget-text-editor\" data-id=\"1fed52a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Le spectacle pla\u00eet \u00e0 tout le monde, quelle que soit la langue ou l&#8217;\u00e2ge, et est un reflet musicalement divertissant et puissamment culturel de l&#8217;histoire et de la beaut\u00e9 de notre maison et de notre pays natal. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2bbd33 elementor-widget elementor-widget-toggle\" data-id=\"b2bbd33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1871\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1871\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1871\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1871\"><div class=\"wp-block-column\"><p class=\"has-black-color has-text-color\">A Musical Taste of Our Canadian Heritage \/ Notre patrimoine canadien, une odyss\u00e9e musicale&#8221; est fortement recommand\u00e9 comme production id\u00e9ale pour mettre en valeur le Canada\u2026 nous recommandons cette production comme parmi les meilleurs que le Canada a \u00e0 offrir\u2026 Le spectacle pla\u00eet \u00e0 tout le monde, peu importe la langue ou l&#8217;\u00e2ge, et est un reflet musicalement divertissant et profond\u00e9ment culturel de l&#8217;histoire et de la beaut\u00e9 de notre maison et de notre pays natal.\u00a0<\/p><p>Glenn Duncan,<br \/>Tourisme &#8211; Ottawa &#8211; Tourisme<\/p><\/div><div class=\"wp-block-column\">\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0791f55\" data-id=\"0791f55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96f4684 elementor-widget elementor-widget-text-editor\" data-id=\"96f4684\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Il touche l&#8217;\u00e2me et \u00e9l\u00e8ve les sens <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07d14f2 elementor-widget elementor-widget-toggle\" data-id=\"07d14f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8191\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8191\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8191\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8191\"><p>La puissante production bilingue de Deborah Davis, savamment recherch\u00e9e,\u00ab A Musical Taste of Our Canadian Heritage \/ Notre patrimoine canadien, une odyss\u00e9e musicale \u00bbest une performance collaborative impr\u00e9gn\u00e9e de musique, de danse, de chanson et de r\u00e9cit historique refl\u00e9tant l&#8217;exp\u00e9rience canadienne, pass\u00e9e et pr\u00e9sente . Cet outil d\u2019enseignement interactif de 90 minutes non seulement suscite un int\u00e9r\u00eat pour la musique et l\u2019histoire de notre pays, mais cultive chez le public un sentiment de fiert\u00e9 nationale, tout en cr\u00e9ant potentiellement une toute nouvelle g\u00e9n\u00e9ration de spectateurs. Il touche l&#8217;\u00e2me et \u00e9l\u00e8ve les sens, quel que soit l&#8217;\u00e2ge du public. C&#8217;est g\u00e9nial! Vous ne serez pas d\u00e9\u00e7u<\/p><p>Donna Kenny<br \/>\u00c9cole interm\u00e9diaire Cedarview<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e0d5a9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9e0d5a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64e2225\" data-id=\"64e2225\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86f56cf elementor-widget elementor-widget-text-editor\" data-id=\"86f56cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Il rassemble plus de 50 interpr\u00e8tes, 100 morceaux de musique et des insignes et costumes authentiques <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2868c8 elementor-widget elementor-widget-toggle\" data-id=\"a2868c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1701\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1701\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1701\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1701\"><p>L\u2019\u00e9mission \u00e0 succ\u00e8s de Deborah Davis: Un go\u00fbt musical de notre patrimoine canadien \/ Notre patrimoine canadien, une odyss\u00e9e musicale est un public incroyable depuis douze ans. Il r\u00e9unit plus de 50 interpr\u00e8tes, 100 morceaux de musique et des insignes et costumes authentiques dans une odyss\u00e9e de 90 minutes de musique, de culture et d&#8217;histoire canadiennes. D&#8217;apr\u00e8s ma propre exp\u00e9rience, ce n&#8217;est pas une production que vous pouvez simplement vous asseoir et regarder passivement. Il est trop \u00e9mouvant et \u00e9difiant de ne pas engager le public \u00e0 un niveau personnel. Deborah a cr\u00e9\u00e9 quelque chose de remarquable et de remarquable. C&#8217;est un vrai talent.<\/p><p>Le d\u00e9put\u00e9. John P. Manley, P.C, OC<br \/>Conseil canadien des chefs d&#8217;entreprise<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-faae63b\" data-id=\"faae63b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-483d682 elementor-widget elementor-widget-text-editor\" data-id=\"483d682\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Vous pourriez ressentir l&#8217;\u00e9nergie et l&#8217;excitation de l&#8217;histoire du Canada <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e485f4a elementor-widget elementor-widget-toggle\" data-id=\"e485f4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2391\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2391\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2391\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2391\"><p>\u2026. Cette production \u00e9tait incroyable !!! C\u2019\u00e9tait passionnant tout au long\u2026 Une exp\u00e9rience palpitante, les costumes \u00e9taient authentiques, les interpr\u00e8tes engageants\u2026 On pouvait ressentir l\u2019\u00e9nergie et l\u2019excitation de l\u2019histoire du Canada\u2026. une occasion vraiment unique de se connecter avec la grande histoire de la chanson et de la danse canadiennes.<\/p><p>M\u00e9lanie<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ecbde36 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ecbde36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1218eb6\" data-id=\"1218eb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfa8e46 elementor-widget elementor-widget-text-editor\" data-id=\"cfa8e46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> L&#8217;\u00e9mission fascine les \u00e9l\u00e8ves du d\u00e9but \u00e0 la fin <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dadc000 elementor-widget elementor-widget-toggle\" data-id=\"dadc000\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2291\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2291\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2291\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2291\"><p>\u00abUn go\u00fbt musical est extr\u00eamement pr\u00e9cieux d&#8217;un point de vue \u00e9ducatif, car il change la fa\u00e7on dont les \u00e9l\u00e8ves regardent l&#8217;histoire et les expose aux arts et aux \u00e9tudes sociales d&#8217;une mani\u00e8re qu&#8217;ils n&#8217;auraient jamais pu vivre autrement. Le spectacle fascine les \u00e9tudiants du d\u00e9but \u00e0 la fin et les emm\u00e8ne dans un voyage \u00e0 travers l&#8217;\u00e9volution de notre pays et de ses habitants. Les liens entre la musique, la danse, les v\u00eatements, les gens et le d\u00e9veloppement physique de la terre sont vifs et fournissent des liens qui ne peuvent pas \u00eatre \u00e9tablis par le biais de manuels, de DVD et de CD. A Musical Taste est une production multidisciplinaire qui regroupe plusieurs des \u00abgrandes id\u00e9es\u00bb pr\u00e9sent\u00e9es dans les documents Arts and Social Studies \/ History \/ Geography du curriculum de l&#8217;Ontario, et elle a un impact \u00e9norme sur les \u00e9tudiants\u2026<\/p><p>Le manuel de l&#8217;enseignant qui l&#8217;accompagne est un atout car il propose de nombreuses activit\u00e9s cr\u00e9atives qui aident les enseignants \u00e0 prolonger l&#8217;excitation de la production dans la salle de classe pendant des semaines par la suite, tout en augmentant les connaissances, l&#8217;appr\u00e9ciation et la participation des \u00e9l\u00e8ves. Le manuel fournit les informations de base n\u00e9cessaires aux enseignants, et les activit\u00e9s permettent une int\u00e9gration avec le document du curriculum des arts du langage de l&#8217;Ontario et les comp\u00e9tences technologiques. C&#8217;est vraiment une fa\u00e7on pratique et novatrice d&#8217;enseigner aux \u00e9l\u00e8ves leur \u00abpays d&#8217;origine et leur pays d&#8217;origine\u00bb tout en int\u00e9grant le contenu de base, et \u00e0 mon avis, cela devrait \u00eatre une composante obligatoire de l&#8217;\u00e9ducation de tous les \u00e9tudiants canadiens. Au nom de tous les enseignants, je vous remercie pour ce merveilleux programme.<\/p><p>Naomi Ventura<br \/>Hazel McCallion Senior Public School<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0918243\" data-id=\"0918243\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2eaf17f elementor-widget elementor-widget-text-editor\" data-id=\"2eaf17f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Une superbe combinaison d&#8217;\u00e9ducation et de divertissement <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dab169 elementor-widget elementor-widget-toggle\" data-id=\"6dab169\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1141\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1141\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1141\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1141\"><div class=\"wp-block-column\"><p>\u201d\u2026 L&#8217;Odyssey Showcase est une superbe combinaison d&#8217;\u00e9ducation et de divertissement. C&#8217;\u00e9tait tr\u00e8s amusant de d\u00e9couvrir les moments forts de la musique canadienne au fil des ans de cette mani\u00e8re novatrice. Deborah Davis et sa distribution sont des interpr\u00e8tes terriblement talentueux et \u00e9nergiques. J&#8217;ai ador\u00e9 !!<\/p><p>Julie Jacobson<\/p><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72d8295 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"72d8295\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bd452b9\" data-id=\"bd452b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a315b6 elementor-widget elementor-widget-text-editor\" data-id=\"7a315b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Incroyable, excitant et envo\u00fbtant! <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b764cb elementor-widget elementor-widget-toggle\" data-id=\"9b764cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1631\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1631\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1631\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1631\"><p>\u201cIncroyable, excitant et envo\u00fbtant! \u2026 S\u00fbr d&#8217;impressionner et de ravir quiconque a la chance de pouvoir le voir! Nous allions encore et encore, cela nous laissait juste en vouloir plus alors que nous dansions &#8220;<\/p><p>Joanne Watts<br \/>Perspectives Eduscho Ltd<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-569e627\" data-id=\"569e627\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4455830 elementor-widget elementor-widget-text-editor\" data-id=\"4455830\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> La production et le manuel ne sont rien de moins que g\u00e9niaux <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-602542e elementor-widget elementor-widget-toggle\" data-id=\"602542e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1001\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1001\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1001\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1001\"><div class=\"wp-block-column\"><p>\u00abLa production et le manuel ne sont rien de moins que brillants. Ils sont tout autant une histoire du Canada qu&#8217;une histoire de divers genres musicaux. Il s&#8217;agit d&#8217;une visite de notre vaste territoire avec un regard sociologique sur nos provinces et territoires. Je n&#8217;h\u00e9siterai absolument pas \u00e0 utiliser des parties de ce manuel dans mes cours coll\u00e9giaux-universitaires et je n&#8217;h\u00e9siterai pas non plus \u00e0 recommander la production et le manuel \u00e0 tous les \u00e9ducateurs. C&#8217;est une excellente contribution \u00e0 l&#8217;apprentissage! \u00bb<\/p><p>Professeur Gerry Cammy<br \/>Coll\u00e8ge du patrimoine, CFRA<\/p><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bc9447 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3bc9447\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c4d475b\" data-id=\"c4d475b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea65a82 elementor-widget elementor-widget-text-editor\" data-id=\"ea65a82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Fascinant, attrayant et pertinent pour la compr\u00e9hension de l&#8217;histoire canadienne. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fe910a elementor-widget elementor-widget-toggle\" data-id=\"7fe910a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1341\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1341\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1341\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1341\"><p>\u00abCe n&#8217;est qu&#8217;un petit mot pour vous faire savoir \u00e0 quel point j&#8217;ai aim\u00e9 votre production de Un go\u00fbt musical de notre patrimoine canadien que j&#8217;ai eu le plaisir de voir \u00e0 Ottawa en mai dernier. Je l&#8217;ai trouv\u00e9 fascinant, attrayant et pertinent pour la compr\u00e9hension de l&#8217;histoire canadienne. Je suis s\u00fbr que les \u00e9l\u00e8ves adoreront le voir et que les enseignants en feront certainement la promotion. \u00bb<\/p><p>Canjita Gomes-Fernandes, PhD<br \/>Commission scolaire English-Montr\u00e9al<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8bdcf83\" data-id=\"8bdcf83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbb7b41 elementor-widget elementor-widget-text-editor\" data-id=\"fbb7b41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> J&#8217;ai vu des \u00e9tudiants qui, de toute \u00e9vidence, voyaient l&#8217;histoire du Canada sous un nouveau jour <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51b2a44 elementor-widget elementor-widget-toggle\" data-id=\"51b2a44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8561\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8561\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8561\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8561\"><p>\u00abLa production met non seulement l&#8217;accent sur le r\u00f4le important de la musique dans l&#8217;histoire canadienne, mais utilise \u00e9galement la musique comme point d&#8217;entr\u00e9e pour des discussions connexes sur l&#8217;ensemble des changements sociaux, \u00e9conomiques, culturels et politiques. Cette approche est conforme \u00e0 l&#8217;orientation actuelle de l&#8217;enseignement et de la recherche interdisciplinaires en \u00e9ducation ainsi qu&#8217;aux efforts visant \u00e0 relier les \u00e9coles et la communaut\u00e9 dans son ensemble.<\/p><p>\u00ab\u2026 De mani\u00e8re cr\u00e9ative et convaincante, Deborah Davis et ses coll\u00e8gues sont \u00e0 l\u2019avant-garde de ces efforts novateurs pour soutenir l\u2019\u00e9tude du pass\u00e9 du Canada. Ils ont montr\u00e9 comment la musique peut stimuler, inspirer et informer les \u00e9l\u00e8ves sur les principales transformations sociales et culturelles dans la construction du Canada moderne. Au cours des derni\u00e8res ann\u00e9es, j\u2019ai eu le plaisir d\u2019exp\u00e9rimenter de premi\u00e8re main l\u2019enthousiasme et l\u2019engagement des \u00e9tudiants qui \u00abgo\u00fbtent\u00bb au patrimoine musical canadien, et mon enthousiasme pour cette approche est le r\u00e9sultat direct de cette exp\u00e9rience. J&#8217;ai vu des \u00e9tudiants qui, de toute \u00e9vidence, voyaient l&#8217;histoire du Canada sous un nouveau jour. Ils \u00e9taient, en effet, en train de devenir des apprenants actifs qui se connectaient avec le pass\u00e9 par leur appr\u00e9ciation et leur \u00e9merveillement devant les sons et les images de notre patrimoine musical\u2026 \u00bb<\/p><p>Professeur Chad Gaffield<br \/>Universit\u00e9 d&#8217;Ottawa<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f887ae elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1f887ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f14c8bd\" data-id=\"f14c8bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55ad657 elementor-widget elementor-widget-text-editor\" data-id=\"55ad657\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Nous avons tout de suite \u00e9t\u00e9 impressionn\u00e9s par l&#8217;originalit\u00e9 de ce concept\u2026 La musique est en effet reconnue depuis longtemps par les \u00e9ducateurs comme un moyen d&#8217;enseigner le plus efficace, <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a18d880 elementor-widget elementor-widget-toggle\" data-id=\"a18d880\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1691\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1691\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1691\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1691\"><p>mais il n&#8217;a jamais \u00e9t\u00e9 appliqu\u00e9 \u00e0 l&#8217;histoire \u00e0 une telle \u00e9chelle. Comme la GRC a jou\u00e9 un r\u00f4le crucial dans le d\u00e9veloppement du Canada, en particulier l&#8217;expansion dans l&#8217;Ouest, nous sommes toujours \u00e0 la recherche de nouvelles fa\u00e7ons de promouvoir cet aspect souvent oubli\u00e9 de notre organisation. En collaboration avec Mme Davis et son \u00e9quipe, nous avons identifi\u00e9 plusieurs morceaux de musique de la GRC qui nous permettraient de promouvoir le r\u00f4le que notre institution a jou\u00e9 dans l&#8217;\u00e9dification de la nation. La Section historique de la GRC a fourni des images et des informations historiques que Mme Davis a combin\u00e9es avec de la musique d&#8217;\u00e9poque. Le r\u00e9sultat \u00e9tait une repr\u00e9sentation tr\u00e8s \u00e9mouvante, mais historiquement exacte du r\u00f4le de la GRC \u00e0 la fin du 19e si\u00e8cle\u2026 Nous avons eu l&#8217;honneur d&#8217;assister \u00e0 la production et avons \u00e9t\u00e9 imm\u00e9diatement impressionn\u00e9s par le haut calibre de tous les interpr\u00e8tes et musiciens. Le produit final \u00e9tait un aper\u00e7u vivant et \u00e9mouvant de la riche histoire du Canada, du contact pr\u00e9-europ\u00e9en au 21e si\u00e8cle. \u00c0 en juger par la r\u00e9ponse du public, nous n\u2019\u00e9tions pas seuls dans notre sentiment. Nous croyons qu&#8217;un avant-go\u00fbt musical de notre patrimoine canadien est une entreprise extr\u00eamement utile qui inculquerait aux Canadiens une plus grande appr\u00e9ciation de notre patrimoine\u2026 \u00bb<\/p><p>Sandy Ramos<br \/>Direction des partenariats strat\u00e9giques et du patrimoine de la GRC<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b9b6a09\" data-id=\"b9b6a09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88179b2 elementor-widget elementor-widget-text-editor\" data-id=\"88179b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Une tapisserie riche et color\u00e9e <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35d08a0 elementor-widget elementor-widget-toggle\" data-id=\"35d08a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5641\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5641\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5641\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5641\"><p>\u2026 Cette exp\u00e9rience musicale \u00e9clectique du patrimoine et de la diversit\u00e9 du Canada a produit une tapisserie riche et color\u00e9e qui r\u00e9veillerait l\u2019esprit de nos anc\u00eatres et nous rappellerait nos liens profonds. Tous les interpr\u00e8tes se sont bien engag\u00e9s avec le public par leur enthousiasme et leur vitalit\u00e9. Bravo \u00e0 tous les solistes et \u00e0 l&#8217;\u00e9quipe d&#8217;Odyssey!<\/p><p>Eithne Barker<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bab097a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bab097a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7412402\" data-id=\"7412402\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a5237a elementor-widget elementor-widget-text-editor\" data-id=\"1a5237a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> La qualit\u00e9 du talent, la cr\u00e9ativit\u00e9 de la performance et la passion des interpr\u00e8tes \u00e9taient inspirantes <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b60be8 elementor-widget elementor-widget-toggle\" data-id=\"2b60be8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4541\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-4541\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4541\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-4541\"><p>\u00abTD Canada Trust fait partie de cette production depuis le d\u00e9but et nous sommes fiers de continuer notre soutien\u2026 J&#8217;ai eu le plaisir d&#8217;assister \u00e0 cette production au moins quatre fois et \u00e0 chaque fois j&#8217;\u00e9tais plus impressionn\u00e9\u2026 la qualit\u00e9 du talent, la cr\u00e9ativit\u00e9 de la performance et de la passion des interpr\u00e8tes \u00e9tait inspirante &#8230; c&#8217;\u00e9tait excellent, repr\u00e9sentant notre culture diversifi\u00e9e et mettant en valeur de nombreuses l\u00e9gendes canadiennes &#8230; la production m&#8217;a rendu fier &#8230; tout simplement, Wow!<\/p><p>Cathy Jowsey<br \/>R\u00e9gion du Nord et de l&#8217;Est de l&#8217;Ontario TD Canada Trust<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a02c932\" data-id=\"a02c932\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b7b8f6 elementor-widget elementor-widget-text-editor\" data-id=\"3b7b8f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Non seulement il est amusant pour les jeunes (et pas si jeunes), mais peut aussi leur en apprendre beaucoup sur la langue et la culture <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9068bc1 elementor-widget elementor-widget-toggle\" data-id=\"9068bc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1511\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1511\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1511\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1511\"><p>\u00abQuel plaisir d&#8217;assister \u00e0 votre spectacle du 1er juin au Mus\u00e9e des civilisations!<br \/>Ma femme et moi avons beaucoup appr\u00e9ci\u00e9, et nous avions avec nous de vieux amis d&#8217;\u00c9cosse qui n&#8217;\u00e9taient jamais all\u00e9s au Canada auparavant &#8230; leur commentaire apr\u00e8s le spectacle \u00e9tait qu&#8217;ils aimaient le Canada &#8230; Permettez-moi aussi de dire, du point de vue de quelqu&#8217;un qui a d\u00e9pens\u00e9 son carri\u00e8re dans le domaine des langues officielles, que votre \u00e9mission est un moyen tr\u00e8s utile de convaincre les Canadiens, et d\u2019autres, de la valeur de l\u2019apprentissage des langues secondes. Il offre non seulement du plaisir aux jeunes (et pas si jeunes), mais peut \u00e9galement leur en apprendre beaucoup sur la langue et la culture. Felicitations et continuez le beau travail.<\/p><p>Charles Barker<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fda0992 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fda0992\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5640692\" data-id=\"5640692\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-492687c elementor-widget elementor-widget-text-editor\" data-id=\"492687c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Il s&#8217;agit d&#8217;une production qui devrait \u00eatre vue par tous les Canadiens (et le monde) <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f535c0 elementor-widget elementor-widget-toggle\" data-id=\"1f535c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3281\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3281\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3281\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3281\"><p>\u00ab\u2026 Depuis plusieurs ann\u00e9es, nous sommes conscients de la cr\u00e9ativit\u00e9, de la vitalit\u00e9, de la vision, de l&#8217;\u00e9nergie, de l&#8217;engagement et de l&#8217;art de Deborah Davis. (Poup\u00e9es en satin et un go\u00fbt musical de notre patrimoine canadien), Tout le monde r\u00eave de r\u00eaves, mais la diff\u00e9rence avec cette femme dynamique est qu&#8217;elle est particuli\u00e8rement capable de r\u00e9aliser ses r\u00eaves .. Cela n&#8217;est d\u00e9montr\u00e9 nulle part plus qu&#8217;avec Un go\u00fbt musical de notre Patrimoine canadien. Presque \u00e0 elle seule, elle a donn\u00e9 vie \u00e0 cette production impressionnante avec un budget limit\u00e9.<\/p><p>Nous nous souvenons bien d&#8217;avoir assist\u00e9 \u00e0 un spectacle public absorb\u00e9 et captiv\u00e9, tout comme le public entier, jeunes et vieux, car l&#8217;histoire du Canada \u00e9tait \u00e9troitement li\u00e9e aux sons distinctifs de la musique canadienne. C\u2019\u00e9tait vraiment une performance virtuose. Cela augmentait l\u2019appr\u00e9ciation du caract\u00e8re distinctif de la musique canadienne.<\/p><p>Quel concept intelligent et attrayant. Il s&#8217;agit d&#8217;une production que tous les Canadiens devraient voir pour rehausser leur fiert\u00e9 \u00e0 l&#8217;\u00e9gard de notre pays. Au-del\u00e0 de cela, les r\u00e9sidents de pays \u00e0 l&#8217;ext\u00e9rieur du Canada en apprendront davantage sur notre patrimoine color\u00e9 &#8211; cela aura un effet profond sur le tourisme. Plus nous y pensons, plus nous sommes convaincus que cette production pourrait devenir un incontournable de l\u2019\u00e9t\u00e9 dans la capitale de notre pays, attirant les Canadiens et les non-Canadiens, tout comme Anne of Green Gable le fait \u00e0 l\u2019\u00cele-du-Prince-\u00c9douard. \u2026 En tant que musiciens, chefs de ch\u0153ur, organisateurs de festivals de musique et gens d&#8217;affaires, nous appuyons sans r\u00e9serve Deborah Davis\u2026 Franchement, nous pensons aussi que cela a du bon sens pour Ottawa et l&#8217;Ontario!\u2026 .C&#8217;est une production qui devrait \u00eatre vue par tous les Canadiens (et le monde) pour rehausser leur fiert\u00e9 envers notre pays. Vraiment, une performance virtuose qui aura un effet profond sur le public.<\/p><p>Lois et Donald Harper<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45327a2\" data-id=\"45327a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55cdb21 elementor-widget elementor-widget-text-editor\" data-id=\"55cdb21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Le point culminant de notre voyage d&#8217;une semaine \u00e0 Ottawa! <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9314d10 elementor-widget elementor-widget-toggle\" data-id=\"9314d10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1541\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1541\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1541\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1541\"><div class=\"wp-block-column\"><p>\u00abUn avant-go\u00fbt musical de notre patrimoine canadien a \u00e9t\u00e9 le point culminant de notre voyage d&#8217;une semaine \u00e0 Ottawa! Ne manquez pas cette merveilleuse et inspirante extravagance musicale et de danse! \u00bb<\/p><p>Jon et Sherry Mahoney<\/p><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4be36a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e4be36a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02be55c\" data-id=\"02be55c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81ae12c elementor-widget elementor-widget-text-editor\" data-id=\"81ae12c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Pendentif tout le spectacle j\u2019ai ressenti une telle fiert\u00e9 envers mon pays <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-798cd5f elementor-widget elementor-widget-toggle\" data-id=\"798cd5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1271\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1271\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1271\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1271\"><p>\u00ab\u2026 Lorsque j\u2019\u00e9tais enfant, je m\u2019ennuyais du cours d\u2019histoire\u2026 et je sais que je n\u2019\u00e9tais pas la seule. Plus maintenant. Pendant tout le spectacle j&#8217;ai ressenti une telle fiert\u00e9 envers mons pays, tout en apprenant son histoire \u00e0 travers les nombreuses sc\u00e8nes historiques..Des Premiers Nations et du peuple Inuit, en passant par le Qu\u00e9b\u00e9cois, le Fran\u00e7ais, les Celtes, les Acadiens \u2026 Et tant d&#8217;autres cultures et styles de musique, j&#8217;ai d\u00e9couvert comme jamais auparavant, les plus importants \u00e9v\u00e9nements historiques prescrits au moyen de chansons, de danses et de courtes pi\u00e8ces de th\u00e9\u00e2tre. Je n\u2019oublierai pas de sit\u020ft ces chapitres de l\u2019Histoire du Canada\u2026 parce que je me suis amus\u00e9e en apprenant\u2026 Pas une seule longeur pendant tout le spectacle, un vrai tour de force! .. \u00bb<\/p><p>Th\u00e9r\u00e8se Gauthier<br \/>L\u2019Hon. Tommy Banks S\u00e9nateur (Alberta)<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6ee07d2\" data-id=\"6ee07d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-704064c elementor-widget elementor-widget-text-editor\" data-id=\"704064c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Il me reste un immense sentiment de fiert\u00e9 d&#8217;\u00eatre Canadien <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ca6f06 elementor-widget elementor-widget-toggle\" data-id=\"2ca6f06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4681\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-4681\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4681\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-4681\"><p>\u00abJe suis all\u00e9 voir Un avant-go\u00fbt musical de notre patrimoine canadien trois fois maintenant\u2026 Ce qui m&#8217;\u00e9tonne, c&#8217;est le nombre de chansons formidables qui sont canadiennes\u2026 Chaque fois que je regarde l&#8217;\u00e9mission, je me retrouve avec un immense sentiment de fiert\u00e9 d&#8217;\u00eatre un Canadien et mes mains me font mal en applaudissant avec la musique et en applaudissant les performances. J\u2019ai la conviction sinc\u00e8re et sinc\u00e8re que chaque Canadien et chaque visiteur de la capitale de notre pays devrait se rendre service et assister \u00e0 ce spectacle incroyable et \u00e9difiant sur le plan spirituel. Vous ne serez pas d\u00e9\u00e7u!&#8221;<\/p><p>Peter Ventura<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8626d86 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8626d86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e23d513\" data-id=\"e23d513\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebad291 elementor-widget elementor-widget-text-editor\" data-id=\"ebad291\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> A favoris\u00e9 un plus grand sentiment de fiert\u00e9 et d&#8217;identit\u00e9 canadienne pour notre communaut\u00e9 autochtone <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8b2e34 elementor-widget elementor-widget-toggle\" data-id=\"a8b2e34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1761\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1761\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1761\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1761\"><p>\u00abNous appr\u00e9cions le respect et la compr\u00e9hension que votre production d\u00e9montre sur les contributions uniques des premiers peuples \u00e0 la musique et \u00e0 l&#8217;histoire du Canada. Nous croyons fermement que la participation \u00e0 cette production a contribu\u00e9 \u00e0 cr\u00e9er une meilleure compr\u00e9hension des premi\u00e8res personnes pour le grand public. De plus, cela a favoris\u00e9 un plus grand sentiment de fiert\u00e9 et d&#8217;identit\u00e9 canadienne pour notre communaut\u00e9 autochtone\u2026 Professionnel et superbe.<\/p><p>Trina Mather Simard<br \/>Turtle Island: tourisme<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-671f444\" data-id=\"671f444\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5415693 elementor-widget elementor-widget-text-editor\" data-id=\"5415693\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> J&#8217;ai ador\u00e9 entendre notre histoire <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b5fe45 elementor-widget elementor-widget-toggle\" data-id=\"1b5fe45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2871\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2871\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2871\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2871\"><p>\u00abJ&#8217;ai ador\u00e9 entendre notre histoire. Ce n&#8217;est pas tous les jours que vous pouvez entendre des chants de gorge inuits, des violons acadiens et de la musique folklorique canadienne en un seul endroit. C&#8217;\u00e9tait incroyable.&#8221;<\/p><p>Sarah Mahoney<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc4bd19 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"dc4bd19\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8b0649b\" data-id=\"8b0649b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2975a4f elementor-widget elementor-widget-text-editor\" data-id=\"2975a4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Quelle merveilleuse fa\u00e7on de d\u00e9couvrir l&#8217;histoire canadienne <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b34a082 elementor-widget elementor-widget-toggle\" data-id=\"b34a082\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1871\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1871\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1871\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1871\"><p>\u00abApr\u00e8s avoir pass\u00e9 trois jours pleins d&#8217;action \u00e0 Ottawa, les \u00e9l\u00e8ves consid\u00e8rent toujours\u00ab Odyssey Showcase \/ \u00abA Musical Taste of Our Canadian Heritage \/ Notre patrimoine canadien, une odyss\u00e9e musicale\u00bb \u00bbcomme leur \u00e9v\u00e9nement pr\u00e9f\u00e9r\u00e9. Quelle merveilleuse fa\u00e7on de VIVRE r\u00e9ellement l&#8217;histoire du Canada. Enseigner par la musique et le th\u00e9\u00e2tre est un m\u00e9dia rarement utilis\u00e9 dans notre syst\u00e8me \u00e9ducatif. Pour les \u00e9tudiants qui ont des d\u00e9fis comme le mien, le spectacle leur a enseign\u00e9 le Canada et leur patrimoine d&#8217;une mani\u00e8re dynamique et impressionnante. Au nom des \u00e9l\u00e8ves de l&#8217;\u00e9cole secondaire Joliette\u2026 Merci pour les souvenirs! Au plaisir de vous revoir en 2012. Veuillez nous tenir au courant. \u00bb<\/p><p>Sharon St Maurice<br \/>\u00c9cole secondaire Joliette<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c8e238a\" data-id=\"c8e238a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1c5bf1 elementor-widget elementor-widget-text-editor\" data-id=\"f1c5bf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Nous fait prendre conscience du r\u00f4le que l&#8217;expression culturelle a jou\u00e9 et continue de jouer dans le renforcement des liens de coh\u00e9sion sociale dans ce pays <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0259407 elementor-widget elementor-widget-toggle\" data-id=\"0259407\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2461\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2461\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2461\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2461\"><p>\u00ab\u2026 \u00c0 mon avis, c\u2019est une \u0153uvre pionni\u00e8re qui, en nous faisant go\u00fbter au riche patrimoine musical du Canada, nous fait tous prendre conscience du r\u00f4le que l\u2019expression culturelle a jou\u00e9 et continue de jouer dans le renforcement des liens de coh\u00e9sion sociale dans ce pays. Nos lois et notre Parlement ne forment que la moiti\u00e9 de l&#8217;\u00e9quation, notre expression culturelle, dont la musique est une partie importante, forme l&#8217;autre.<\/p><p>Dr Paul Benoit, PhD<br \/>Bureau du commerce international du ministre du Commerce international et du ministre de la porte d&#8217;entr\u00e9e du Pacifique et des Olympiques de Vancouver-Whistler<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ad6c47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ad6c47\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c51f05d\" data-id=\"c51f05d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-073978b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"073978b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Don de critiques de jazz<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c027320 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c027320\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;2.5&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpolyline points=&#039;0,18 12,6 24,18 &#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cb0233 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3cb0233\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-05728cb\" data-id=\"05728cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-637738b elementor-widget elementor-widget-text-editor\" data-id=\"637738b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Avec la chanson, la danse et les contes, les publics de tous \u00e2ges et en particulier les \u00e9tudiants ont \u00e9t\u00e9 guid\u00e9s \u00e0 travers l\u2019importance de l\u2019histoire et de la culture du Canada\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b1d587 elementor-widget elementor-widget-toggle\" data-id=\"5b1d587\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9551\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9551\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9551\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9551\"><p>\u00abAu cours des 14 derni\u00e8res ann\u00e9es, j&#8217;ai eu le plaisir de faire partie des productions d&#8217;Odyssey Showcase. Je sens de tout c\u0153ur que leurs productions sont des ic\u00f4nes d&#8217;une valeur \u00e9ducative et de divertissement inestimable.<br \/>Je m&#8217;appelle Darin Kyle. Je suis le premier champion du monde canadien de claquettes. Je suis un conf\u00e9rencier d&#8217;honneur et un activiste local du \u00abd\u00e9veloppement communautaire\u00bb \u00e0 Ottawa. Mes racines dans cette ville sont profondes. Et j&#8217;ai un profond respect pour la fa\u00e7on dont Deborah Davis, son \u00e9quipe et ses acteurs ont eu un impact sur la vie des \u00e9tudiants. Avec la chanson, la danse et les contes, les publics de tous \u00e2ges et en particulier les \u00e9tudiants ont \u00e9t\u00e9 guid\u00e9s par l\u2019importance de l\u2019histoire et de la culture du Canada.<br \/>Odyssey Showcase se consacre \u00e0 trouver les bons talents pour faire le travail et le fait extraordinairement bien. Je suis d&#8217;avis que si on lui donne la possibilit\u00e9 d&#8217;appuyer le projet Canada Speaks, alors la seule ligne de conduite consiste \u00e0 apporter tout votre soutien \u00e0 l&#8217;initiative et \u00e0 surfer sur la vague de succ\u00e8s qui s&#8217;ensuivra. Par exp\u00e9rience, ce sera un partenariat fond\u00e9 sur un succ\u00e8s mutuellement assur\u00e9. Je vous invite \u00e0 vivre ce partenariat par vous-m\u00eame. \u00bb Darin David Kyle<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-05edb87\" data-id=\"05edb87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d3d3d8 elementor-widget elementor-widget-text-editor\" data-id=\"9d3d3d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Surtout, Deborah est l&#8217;une de ces rares personnes qui englobe un talent musical avec un sens profond du but\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da83748 elementor-widget elementor-widget-toggle\" data-id=\"da83748\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2291\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2291\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2291\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2291\"><p>\u00abDeborah Davis est une personne que les gens respectent et admirent avec beaucoup d&#8217;affection. En partie \u00e0 cause de l&#8217;\u00e9nergie incroyable qu&#8217;elle est pr\u00eate \u00e0 consacrer \u00e0 ce en quoi elle croit, mais plus encore, c&#8217;est parce que c&#8217;est ce qu&#8217;elle ressent pour chacun d&#8217;eux. Les acteurs et l&#8217;\u00e9quipe, les sponsors, les enseignants, les enfants, les \u00e9tudiants et tous ceux associ\u00e9s \u00e0 tout ce que Deborah touche tous la soutiennent parce qu&#8217;elle donne vie d&#8217;une mani\u00e8re dont les autres ne peuvent que r\u00eaver, tant de choses sont \u00e9mouvantes, belles, inspirantes et, tout simplement, les meilleures en nous. Deborah rassemble les gens \u00e0 travers les arts.<\/p><p>\u00ab\u2026 Surtout, Deborah est l&#8217;une de ces rares personnes qui englobe un talent musical avec un sens profond du but. Sa ferme conviction de soutenir la culture canadienne lui a donn\u00e9 une \u00abraison d\u2019\u00eatre\u00bb. Mon association en tant que directrice musicale pour ses nombreux efforts a \u00e9t\u00e9 un grand voyage qui remonte \u00e0 vingt ans, y compris des projets tels que Un go\u00fbt musical de notre patrimoine canadien, Satin Dolls, What is this Thing called Jazz, Choonga Changa et divers autres spectacles musicaux.<br \/>Je m&#8217;en voudrais de ne pas mentionner sa g\u00e9n\u00e9rosit\u00e9 de faire ressortir et de payer personnellement des centaines d&#8217;enfants \u00e9conomiquement d\u00e9favoris\u00e9s au cours des dix-neuf derni\u00e8res ann\u00e9es pour avoir l&#8217;opportunit\u00e9 de voir les productions \u2026\u2026 Deborah est tr\u00e8s m\u00e9ritante et attendue depuis longtemps pour tout prix en les arts. &#8220;<br \/>Peter Beaudoin, directeur musical et musicien<\/p><p>\u00c0 propos de Peter: Peter a plus de trente ans d&#8217;exp\u00e9rience en tant que musicien, batteur et chef de groupe. Il a \u00e9galement effectu\u00e9 neuf tourn\u00e9es mondiales de spectacles des Forces canadiennes en Bosnie, en Afghanistan et \u00e0 Duba\u00ef. Il a eu une carri\u00e8re impressionnante en tant qu&#8217;interpr\u00e8te et musicien d&#8217;enregistrement respect\u00e9 et tr\u00e8s recherch\u00e9 avec de nombreux artistes canadiens et internationaux de classe mondiale, dont Harry Chapin, Petula Clark, Rita Coolidge et Rob McConnell (Boss Brass) pour n&#8217;en nommer que quelques-uns. Peter travaille avec Deborah Davis depuis 1997 sur un certain nombre de projets en tant que directeur musical, notamment Satin Dolls, What is this Thing Called Jazz, Canada Roars et le Canadian Musical Odyssey Ensemble.<br \/>Peter Beaudoin<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7035a1e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7035a1e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a938f4e\" data-id=\"a938f4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2d49a5 elementor-widget elementor-widget-text-editor\" data-id=\"f2d49a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Il est toujours merveilleux d&#8217;assister \u00e0 un hommage \u00e0 une forme d&#8217;art am\u00e9ricaine, car cela fait basculer toute la diversit\u00e9 qui contribue \u00e0 sa cr\u00e9ation. Histoire et culture du Canada 2. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d78548 elementor-widget elementor-widget-toggle\" data-id=\"1d78548\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3091\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3091\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3091\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3091\"><p>\u00abC&#8217;est toujours merveilleux d&#8217;assister \u00e0 un hommage \u00e0 une forme d&#8217;art am\u00e9ricaine, car cela fait basculer toute la diversit\u00e9 qui contribue \u00e0 sa cr\u00e9ation. L&#8217;exp\u00e9rience am\u00e9ricaine, dans son essence m\u00eame, t\u00e9moigne de l&#8217;implication de tant de cultures et d&#8217;horizons et des b\u00e9n\u00e9dictions qui en \u00e9mergent.<br \/>Le jazz est un tr\u00e9sor am\u00e9ricain, un cadeau offert par ses habitants au monde, repr\u00e9sentant musicalement et rythmiquement sa douleur, sa joie, son \u00e9nergie, sa jeunesse, son insouciance et son \u00e9merveillement. Cela se voit clairement dans la pr\u00e9sentation de Gift of Jazz de Deborah Davis, qui raconte la naissance, la r\u00e9surrection et le d\u00e9ploiement de cette forme d\u2019art sur la sc\u00e8ne mondiale.<br \/>Au c\u0153ur de cette performance, nous voyons et ressentons l&#8217;\u00e2me de la diaspora africaine. Nous entendons l&#8217;agonie du passage du milieu et l&#8217;espoir d&#8217;un peuple nouvellement lib\u00e9r\u00e9 de l&#8217;esclavage. Alors que le paysage et le si\u00e8cle tournent et que l&#8217;Am\u00e9rique commence \u00e0 fl\u00e9chir, nous assistons aux influences des classiques europ\u00e9ens et de la modernit\u00e9 sur la pr\u00e9sentation du jazz dans le courant dominant de la culture. La pr\u00e9sentation \u00abGift\u00bb rend hommage aux grands interpr\u00e8tes de Bessie Smith, Louis \u2018Satchmo\u2019 Armstrong, Fats Waller et bien d\u2019autres.<br \/>Tous les interpr\u00e8tes et musiciens de \u00abGift\u00bb sont des artisans d\u00e9vou\u00e9s et des amoureux des arts et leur professionnalisme est \u00e9vident dans cette performance.<br \/>Il est tr\u00e8s clair que Deborah Davis et Segue to Jazz ont une gagnante dans le \u00abDon du jazz\u00bb alors qu\u2019elle continue de partager cette exp\u00e9rience avec la communaut\u00e9 du Grand Ottawa. Lorsqu&#8217;il est pr\u00e9sent\u00e9 \u00e0 nouveau, il est \u00e0 voir absolument. Michael Curtis Hanna<\/p><p>\u00c0 propos de Michael: Michael a eu la chance de vivre l&#8217;exp\u00e9rience de vie unique dans une communaut\u00e9 avec Sarah Vaughn, Al Hibler, Thad Jones, Nat Adderly et une foule de musiciens renomm\u00e9s au coin de la rue de chez lui. N\u00e9 \u00e0 Detroit, Michigan et \u00e9lev\u00e9 \u00e0 Teaneck, New Jersey, il a \u00e9t\u00e9 plong\u00e9 dans une grande partie du paysage musical changeant des 50 derni\u00e8res ann\u00e9es.<br \/>\u00c0 la recherche de J\u00e9sus et de la musique gospel Michael a chant\u00e9 dans des chorales d&#8217;\u00e9glises de Detroit \u00e0 Ottawa. En tant que chanteur solo, Michael a tourn\u00e9 avec et pour son p\u00e8re, feu Sir Roland Hanna aux \u00c9tats-Unis et au Japon. Ayant un penchant pour l\u2019harmonie vocale masculine, Michael a nourri cet amour du chant avec des groupes masculins a cappella, dont le Canadian Men\u2019s Chorus de Toronto.<br \/>Michael dirige actuellement Rahanna Music Inc. et a d\u00e9velopp\u00e9 plus de 300 compositions de Sir Roland Hanna. On le retrouve \u00e9galement sur plusieurs CD en plus de se produire \u00e0 Ottawa et \u00e0 l\u2019\u00e9tranger. Michael Hanna<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5442057\" data-id=\"5442057\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38f5c2e elementor-widget elementor-widget-text-editor\" data-id=\"38f5c2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Odyssey pr\u00e9sente la Saint-Valentin ultime au jazz <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-643f721 elementor-widget elementor-widget-toggle\" data-id=\"643f721\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1051\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1051\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1051\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1051\"><div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> La musique jazz a certainement cr\u00e9\u00e9 suffisamment de standards romantiques pour se glisser dans la cr\u00e9ation d&#8217;une liste de lecture pour la Saint-Valentin pour ce d\u00eener aux chandelles avec votre ch\u00e9rie. Ella et Louis chantant &#8220;Cheek to Cheek&#8221;, Miles apaisant corne sur &#8220;Stella by Starlight&#8221;, le chant sensuel du chant des f\u00eates &#8220;Let&#8217;s Do It (Let&#8217;s Fall In Love)&#8221; et, bien s\u00fbr, le triste Chet et son dr\u00f4le de Valentine. \/ p>\nLorsque vous plongez vos orteils dans le vaste oc\u00e9an du jazz et que vous recherchez l\u2019amour, les eaux dans lesquelles vous vous aventurez constituent une belle le\u00e7on d\u2019histoire de musique romantique.\n\nEn ce jour, cependant, o\u00f9 les lumi\u00e8res \u00e9taient tamis\u00e9es, les chocolats d\u00e9ball\u00e9s et tout le monde semblait se promener avec un bouquet de roses, l&#8217;Odyssey Showcase est all\u00e9 encore plus loin dans ces eaux. Que vous soyez un aficionado du genre ou que vous soyez curieux de conna\u00eetre ses racines, The Gift of Jazz: From Africa to New Orleans to the True North Strong and Free \u00e9tait un spectacle avec beaucoup de choses \u00e0 aimer lors d&#8217;une journ\u00e9e consacr\u00e9e \u00e0 ce sentiment m\u00eame.\n\nCe fut un voyage \u00e0 travers les d\u00e9cennies \u00e0 la National Gallery mais cette fois-ci, ce n&#8217;\u00e9tait pas par les \u0153uvres d&#8217;art sur les murs. Des champs de coton aux bancs d&#8217;\u00e9glise o\u00f9 le glorieux gospel de \u00abAmazing Grace\u00bb et \u00abSwing Low Sweet Chariot\u00bb r\u00e9sonnait au ciel, les d\u00e9buts du jazz entre les mains (et les voix) de Michael Curtis Hanna et Deborah Davis, eh bien, tout simplement paradisiaque!\n\nD\u00e8s le d\u00e9but, cependant, on nous a montr\u00e9 que m\u00eame \u00e0 ses d\u00e9buts hymnaires, les graines du jazz pouvaient encore balancer. Cette \u00e9glise s&#8217;est transform\u00e9e en un saut d&#8217;obstacles \u00e0 la Nouvelle-Orl\u00e9ans lorsque ces saints sont entr\u00e9s et ont ensuite continu\u00e9 cette marche en un rien de temps alors que &#8220;The Entertainer&#8221; de Scott Joplin offrait un interm\u00e8de avant que les ann\u00e9es folles aient Hanna \u00e9clater son meilleur Louis Armstrong. &#8220;Basin Street Blues&#8221; et &#8220;Birth of the Blues&#8221; avaient ce critique imaginant une bo\u00eete de nuit enfum\u00e9e quelque part vers minuit o\u00f9 le son d&#8217;une trompette se propageait tout le long de la Main o\u00f9 il semblait que m\u00eame les lampadaires se balan\u00e7aient.\n\nAvant que les choses ne se terminent trop, le chica, le chica boom rendu c\u00e9l\u00e8bre par Carmen Miranda a rachet\u00e9 le champion du monde de claquettes Darin Kyle et tout aussi impressionnante Bernadette B\u00e9langer. Chaque fois que l&#8217;un, l&#8217;autre et surtout les deux sont mont\u00e9s sur sc\u00e8ne, cela a s\u00e9duit le public. Certains dans la foule ne pouvaient plus rester assis et ont trouv\u00e9 qu\u2019\u00eatre debout et boppin \u2019\u00e9tait la meilleure fa\u00e7on d\u2019\u00eatre.\n\nLe premier acte contenait un magnifique hommage aux Satin Dolls de la musique jazz. Des femmes comme Billie Holiday, Dinah Washington, Sarah Vaughn, Ella Fitzgerald et Bessie Smith ont re\u00e7u un hommage appropri\u00e9 dans la voix de Davis et Sheril Shaw.\n\nL\u2019histoire \u00e9tait intercal\u00e9e entre les musiques, le joueur de haies olympique canadien Sekou Kaba servant de narrateur de l\u2019\u00e9mission, expliquant le contexte des chansons choisies et leur place dans l\u2019h\u00e9ritage du jazz. Les acteurs ont contribu\u00e9 \u00e0 accentuer cela via leurs repr\u00e9sentations de personnages historiques dans et en dehors de la musique. Booker T. Washington de Darin Kyle, Harriet Tubman de Tifanni Kenny et Viola Desmond de Simone Shepherd se sont particuli\u00e8rement d\u00e9marqu\u00e9s. Parmi les autres invit\u00e9s de la soir\u00e9e figuraient le pr\u00e9sentateur de CTV News Stefan Keyes et le po\u00e8te laur\u00e9at Jamaal Jackson Rogers.\n\nBien s\u00fbr, vous ne pouvez pas avoir de jazz sans un groupe qui peut le battre jusqu&#8217;\u00e0 11 autant qu&#8217;il peut tirer sur les cordes de votre c\u0153ur avec un groove ralenti. Ren\u00e9 Lavoie s&#8217;est occup\u00e9 de cette affaire au saxophone avec Ed Bimm au piano, Ken Kanwisher \u00e0 la contrebasse et Gino Scaffidi \u00e0 la guitare \u00e9lectrique. Pourtant, c\u2019est peut-\u00eatre le directeur musical et batteur du groupe, Peter Baudoin, qui a vol\u00e9 la vedette.\n\nAlors que le deuxi\u00e8me set atteignait un crescendo sur &#8220;Sing Sing&#8221;, Kyle se promenait \u00e0 nouveau avec fantaisie.\nCe qui s&#8217;est pass\u00e9 a \u00e9t\u00e9 une bataille de tambours de couplets de claquettes \u00e0 claquettes qui a presque d\u00e9clench\u00e9 les alarmes d&#8217;incendie. Ohhhhh ouais, il faisait si chaud!\n\nBeaudoin a claqu\u00e9 les peaux aussi vite que les pieds de Kyle pouvaient le porter sans aucun vainqueur dans le duel musical (mais nous, le public, bien s\u00fbr). Tout cela a conduit \u00e0 un m\u00e9lange jubilatoire de Motown qui nous a fait danser dans nos si\u00e8ges.\n\nAinsi, alors que cette Saint-Valentin \u00e9tait s\u00fbre d&#8217;apporter des d\u00e9lectables sucr\u00e9s, des buffets de fleurs et, j&#8217;en suis s\u00fbr, quelque chose d&#8217;or, de diamant et de brillant pour certains, ce m\u00e9lomane \u00e9tait plus que satisfait de ce que Odyssey Showcase m&#8217;a donn\u00e9 Le jazz. Bilan de Earth to Andre 2019\n\n<\/div>\n<div class = \"wp-block-column\"> <\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fcdb0de elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fcdb0de\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-946f35d\" data-id=\"946f35d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93c1bb3 elementor-widget elementor-widget-text-editor\" data-id=\"93c1bb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> En tant qu&#8217;enseignant de 6e ann\u00e9e, je vois The Gift of Jazz &#8220;comme un&#8221; cadeau &#8220;\u00e9ducatif pour tous les \u00e9l\u00e8ves de niveau junior-senior\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-000503a elementor-widget elementor-widget-toggle\" data-id=\"000503a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2051\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2051\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2051\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2051\"><p>\u00abThe Gift of Jazz c\u00e9l\u00e8bre l&#8217;impact profond et la diversit\u00e9 de la culture et de l&#8217;histoire noires et d\u00e9peint une narration musicale des contributions des Afro-Am\u00e9ricains au d\u00e9veloppement de la musique. The Gift of Jazz est engageant, dynamique\u2026 et incontournable pour les familles et les groupes scolaires. En tant que parent d&#8217;un enfant de 9 et 14 ans, je peux honn\u00eatement dire qu&#8217;ils \u00e9taient tous les deux fascin\u00e9s par la production. Ensuite, nous nous sommes engag\u00e9s dans de merveilleuses discussions sur la vie des Afro-Am\u00e9ricains, les droits civiques et la fa\u00e7on dont l&#8217;humeur et l&#8217;exp\u00e9rience ont contribu\u00e9 au d\u00e9veloppement de diff\u00e9rents genres de jazz. En tant qu&#8217;enseignant de 6e ann\u00e9e, je vois le don du jazz comme un \u00abcadeau\u00bb \u00e9ducatif pour tous les \u00e9l\u00e8ves de niveau junior-senior. Avec la richesse de la justice sociale et des liens avec les programmes scolaires que la production fournit, c&#8217;est le compl\u00e9ment id\u00e9al pour soutenir le Mois de l&#8217;histoire des Noirs. Naomi Ventura, Hazel McCallion Sr. P.S.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1a39411\" data-id=\"1a39411\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c03953b elementor-widget elementor-widget-text-editor\" data-id=\"c03953b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Mes invit\u00e9s et moi avons appr\u00e9ci\u00e9 chaque chanson, les chanteurs, les danseurs, les acteurs et les notes de discours qui ont encadr\u00e9 et contextualis\u00e9 les chansons\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb085c6 elementor-widget elementor-widget-toggle\" data-id=\"eb085c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2461\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2461\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2461\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2461\"><p>\u00abInvit\u00e9s Mes invit\u00e9s et moi avons appr\u00e9ci\u00e9 chaque chanson, les chanteurs, les danseurs, les acteurs et les discours qui encadraient et contextualisaient les chansons. . . . les toiles de fond et les diapositives, le groupe, l&#8217;\u00e9clairage, la chor\u00e9graphie, les niveaux sonores &#8211; tout est fabuleux! Un spectacle formidable. . . . . il doit \u00eatre r\u00e9p\u00e9t\u00e9 chaque ann\u00e9e et plus d&#8217;un soir. . . avec des \u00e9tudiants invit\u00e9s de chaque lyc\u00e9e de la ville, pour apprendre quelque chose sur la musique et l&#8217;histoire noires. \u00bbFloralove Katz<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0cd39c6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0cd39c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cc2e9f1\" data-id=\"cc2e9f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d24517 elementor-widget elementor-widget-text-editor\" data-id=\"7d24517\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> La musique vivante, le groupe impeccable et les interpr\u00e8tes ont diverti le public tout au long\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb7976b elementor-widget elementor-widget-toggle\" data-id=\"eb7976b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2461\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2461\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2461\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2461\"><p>\u00abC&#8217;est la deuxi\u00e8me ann\u00e9e que nous assistons aux performances de Deborah Davis et Odyssey Showcase, et nous avons ador\u00e9 chaque minute. La musique vivante, le groupe impeccable et les interpr\u00e8tes ont diverti le public tout au long. Cette ann\u00e9e, &#8220;Gift of Jazz&#8221; a pr\u00e9sent\u00e9 une merveilleuse s\u00e9lection de chansons incroyables des plus grands chanteurs de jazz du si\u00e8cle dernier\u2026 .Deborah, Stefan Keyes, Michael C. Hanna et le danseur de claquettes Darin Kyle ont gard\u00e9 le niveau d&#8217;\u00e9nergie \u00e9lev\u00e9, avec le public rebondissant \u00e0 le rythme de leurs chansons tout au long. Il n&#8217;y a pas eu d&#8217;accalmie dans la performance du d\u00e9but \u00e0 la fin. La qualit\u00e9 de la musique, de la danse et du chant \u00e9tait une source d&#8217;inspiration. Anna Rubinstein<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f71be6c\" data-id=\"f71be6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bdf564 elementor-widget elementor-widget-text-editor\" data-id=\"3bdf564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Spectacle spectaculaire! &#8230;. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d6465 elementor-widget elementor-widget-toggle\" data-id=\"e3d6465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2381\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2381\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2381\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2381\"><p>\u00abSpectacle spectaculaire! Nous avons eu droit \u00e0 une soir\u00e9e absolument \u00e9poustouflante &#8211; \u00e0 la fois visuellement et musicalement, des costumes d&#8217;\u00e9poque aux voix \u00e9tonnantes, fortes et puissantes de Deborah, Michael et Stefan !!!<\/p><p>\u2026 .De l&#8217;Afrique \u00e0 nos jours\u2026 .une histoire bien racont\u00e9e \u00e0 travers la musique. F\u00e9licitations \u00e0 la TD et \u00e0 tous les membres de The Gift of Jazz. \u00bb Marques Raffi<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0815ece elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0815ece\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-01b59f1\" data-id=\"01b59f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc21dfe elementor-widget elementor-widget-text-editor\" data-id=\"fc21dfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> The Gift of Jazz est une exp\u00e9rience qui capture parfaitement le voyage \u00e9clectique de l&#8217;\u00e9volution musicale nord-am\u00e9ricaine. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9043dad elementor-widget elementor-widget-toggle\" data-id=\"9043dad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1511\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1511\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1511\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1511\"><p>\u00abThe Gift of Jazz est une exp\u00e9rience qui capture parfaitement le parcours \u00e9clectique de l&#8217;\u00e9volution musicale nord-am\u00e9ricaine. L&#8217;\u00e9quipe diversifi\u00e9e est compos\u00e9e de professionnels d\u00e9di\u00e9s \u00e0 diffuser l&#8217;immense beaut\u00e9 et la joie que le jazz offre \u00e0 l&#8217;esprit! C&#8217;est un privil\u00e8ge de cr\u00e9er avec cette production, et je pr\u00e9vois \u00e0 chaque \u00e9tape que nous aurons l&#8217;opportunit\u00e9 de partager l&#8217;histoire et l&#8217;\u00e9merveillement du jazz.<br \/>Jamall Jackson Rogers (juste Jamaal)<br \/>Lien YouTube Just Jamaal<br \/>\u00c0 propos de Jamaal: Jamaal Jackson Rogers est un po\u00e8te prim\u00e9, des artistes hip-hop, un \u00e9ducateur artistique et un entrepreneur cr\u00e9atif. Il est actuellement po\u00e8te laur\u00e9at anglais d\u2019Ottawa et a fait conna\u00eetre son travail \u00e0 un public national et \u00e9tranger. Ses moments marquants sont quand il \u00e9tablit des liens intimes avec ses participants lors de ses performances et \u00e9changes d&#8217;ateliers.<\/p><p>Ses sujets vont de la maturit\u00e9 \u00e9motionnelle \u00e0 la justice sociale, des luttes de la vie quotidienne \u00e0 la condition humaine. Il est p\u00e8re de cinq enfants et r\u00e9side \u00e0 Ottawa, au Canada, utilisant la capitale nationale et son studio de spectacle, THE ORIGIN ARTS &amp; COMMUNITY CENTER, comme tremplin pour pratiquer, enseigner, encadrer et d\u00e9fendre les arts.<br \/>Jamaal Jackson Rogers<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ee29cd0\" data-id=\"ee29cd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2afad93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2afad93\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66e1f0c\" data-id=\"66e1f0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca11cd0 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ca11cd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avis sur Canada Roars\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d205f8f elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d205f8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;2.5&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpolyline points=&#039;0,18 12,6 24,18 &#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-572d79a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"572d79a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5195bea\" data-id=\"5195bea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-494b249 elementor-widget elementor-widget-text-editor\" data-id=\"494b249\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> En tant qu&#8217;Am\u00e9ricain vivant au Canada, j&#8217;ai \u00e9t\u00e9 surpris d&#8217;apprendre \u00e0 quel point l&#8217;histoire musicale du Canada a ajout\u00e9 et chang\u00e9 le monde &#8230; <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e54c21f elementor-widget elementor-widget-toggle\" data-id=\"e54c21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2401\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2401\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2401\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2401\"><p>\u00abJ&#8217;ai assist\u00e9 \u00e0 ce spectacle et j&#8217;ai \u00e9t\u00e9 profond\u00e9ment et totalement transperc\u00e9 par le talent, la chor\u00e9graphie, le contenu et les informations du spectacle le plus agr\u00e9able que j&#8217;ai vu depuis de nombreuses ann\u00e9es. En tant qu\u2019am\u00e9ricain vivant au Canada, j\u2019ai \u00e9t\u00e9 surpris d\u2019apprendre \u00e0 quel point l\u2019histoire musicale du Canada a ajout\u00e9 et chang\u00e9 le monde. Les \u00e9coliers qui fr\u00e9quentaient \u00e9taient captiv\u00e9s et attentifs et \u00e9taient une joie de les regarder agiter leurs bras et chanter. Je recommande vivement ce spectacle \u00e0 tous ceux qui aiment la musique! Deborah Davis \u00e9tait une pure joie et son talent transcende de nombreuses \u00e9poques musicales. Bravo \u00e0 un tr\u00e8s grand spectacle!<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d5a578\" data-id=\"6d5a578\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e1e118 elementor-widget elementor-widget-text-editor\" data-id=\"4e1e118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> L&#8217;\u00e9quipe s&#8217;est consult\u00e9e moi-m\u00eame et les autres ambassadeurs culturels des Premi\u00e8res Nations pour s&#8217;assurer que la culture, les gens et l&#8217;histoire sont pr\u00e9sent\u00e9s de mani\u00e8re appropri\u00e9e. Ces \u00e9tapes sont tr\u00e8s appr\u00e9ci\u00e9es et ont donc renforc\u00e9 notre participation \u00e0 l&#8217;Odyss\u00e9e musicale 2. <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98659d7 elementor-widget elementor-widget-toggle\" data-id=\"98659d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1591\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1591\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1591\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1591\"><p>\u00abJe m&#8217;appelle Jason Gullo Mullins de la nation Cherokee. Je suis un ambassadeur culturel des Premi\u00e8res Nations, un \u00e9ducateur, un excellent artiste et un artiste de la sc\u00e8ne. Mon r\u00f4le en tant qu&#8217;ambassadeur culturel est d&#8217;\u00e9duquer et de repr\u00e9senter correctement les Premi\u00e8res Nations.<\/p>\n<p>Je joue avec l\u2019Odyssey Showcase et l\u2019ensemble Canadian Musical Odyssey depuis 12 ans. Au cours de cette p\u00e9riode, nous avons \u00e9t\u00e9 accueillis \u00e0 bras chaleureux dans le casting en tant que famille. L&#8217;\u00e9quipe s&#8217;est consult\u00e9e moi-m\u00eame et les autres ambassadeurs culturels des Premi\u00e8res Nations pour s&#8217;assurer que la culture, les gens et l&#8217;histoire sont pr\u00e9sent\u00e9s de mani\u00e8re appropri\u00e9e. Ces \u00e9tapes sont tr\u00e8s appr\u00e9ci\u00e9es et ont donc renforc\u00e9 notre participation \u00e0 l&#8217;Odyss\u00e9e musicale.<\/p>\n<p>Canada Roars et Canada Speaks sont une superbe mise en page de l&#8217;histoire du Canada, le format de l&#8217;enseignement par les arts permet aux jeunes d&#8217;apprendre plus facilement, surtout lorsque vous les divertissez et les engagez avec des m\u00e9diums auxquels ils peuvent tous s&#8217;identifier: musique live, danse, chant et th\u00e9\u00e2tre. .<\/p>\n<p>J&#8217;ai h\u00e2te de jouer \u00e0 nouveau avec le casting bient\u00f4t. \u00bbJason.G.Mullins<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3e8624 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a3e8624\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-06ab599\" data-id=\"06ab599\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50aa29e elementor-widget elementor-widget-text-editor\" data-id=\"50aa29e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Une merveilleuse occasion de d\u00e9montrer les nombreuses contributions positives que les Premiers Peuples ont apport\u00e9es ici m\u00eame dans notre territoire traditionnel d&#8217;Odawa, \u00e9galement connu sous le nom d&#8217;Ottawa\u2026. <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-091cc4b elementor-widget elementor-widget-toggle\" data-id=\"091cc4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9551\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9551\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9551\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9551\"><p>\u00abBrilli Un outil p\u00e9dagogique brillant\u2026 les projets Canada Roars et Canada Speaks offrent une merveilleuse occasion de d\u00e9montrer les nombreuses contributions positives que les Premiers Peuples ont apport\u00e9es ici m\u00eame sur notre territoire traditionnel d&#8217;Odawa, \u00e9galement connu sous le nom d&#8217;Ottawa\u2026\u00bb Sarah Decontie<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e80a256\" data-id=\"e80a256\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a6275f elementor-widget elementor-widget-text-editor\" data-id=\"1a6275f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Vous pouvez voir le changement inspir\u00e9 par l&#8217;\u00e9ducation \u00e0 travers les arts, l&#8217;\u00e9vidence est dans leurs yeux et dans leurs sourires! &#8230;. <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7aa0ea elementor-widget elementor-widget-toggle\" data-id=\"a7aa0ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1751\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1751\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1751\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1751\"><p>\u00abLorsque je d\u00e9cris le r\u00f4le de Pauline Johnson, c\u2019est toujours une b\u00e9n\u00e9diction de voir l\u2019esprit et les curiosit\u00e9s des jeunes s\u2019ouvrir lorsqu&#8217;ils d\u00e9couvrent certains des tr\u00e9sors cach\u00e9s de l\u2019histoire canadienne. De nombreux participants arrivent sans savoir qui sont les personnages, mais quand ils partent, vous pouvez voir le changement inspir\u00e9 par l&#8217;\u00e9ducation \u00e0 travers les arts, l&#8217;\u00e9vidence est dans leurs yeux et dans leurs sourires! Rhonda Doxtator<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2648744 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2648744\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e1e6d8\" data-id=\"1e1e6d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc9b510 elementor-widget elementor-widget-text-editor\" data-id=\"bc9b510\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Un \u00e9l\u00e8ve de la Premi\u00e8re Nation Mohawk qui a fr\u00e9quent\u00e9 Canada Speaks \u00e9tait ravi d&#8217;avoir pu partager une partie de son histoire avec ses camarades de classe\u2026. <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-505353e elementor-widget elementor-widget-toggle\" data-id=\"505353e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8421\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8421\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8421\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8421\"><p>\u00abTravailler avec Odyssey Showcase sur Canada Roars et Canada Speaks a \u00e9t\u00e9 une exp\u00e9rience tellement riche, non seulement pour moi, mais aussi pour les \u00e9tudiants. Je fais partie de la m\u00eame culture que le personnage que je repr\u00e9sente; Hiawatha, donc je ressens une connexion si profonde avec lui et cela se ressent pour le public, quel que soit son \u00e2ge, car tout le monde est toujours d\u00e9sireux d&#8217;en savoir plus et surpris quand ils apprennent quelque chose de nouveau. Un \u00e9l\u00e8ve de la Premi\u00e8re nation Mohawk qui a particip\u00e9 \u00e0 Canada Speaks \u00e9tait enthousiasm\u00e9 parce qu&#8217;il a pu partager une partie de son histoire avec ses camarades de classe. Il pensait que c&#8217;\u00e9tait \u00abvraiment cool\u00bb que je sois Mohawk et que je d\u00e9peigne une figure importante qu&#8217;il connaissait et \u00e0 laquelle il pouvait s&#8217;identifier!<\/p>\n<p>\u00catre en mesure de mettre en valeur cette figure importante d&#8217;une mani\u00e8re exempte de st\u00e9r\u00e9otypes et d&#8217;hypoth\u00e8ses est exactement ce dont les jeunes du Canada ont besoin. Canada Speaks est la plateforme id\u00e9ale pour cela.<\/p>\n<p>Will Lafrance<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6c6a930\" data-id=\"6c6a930\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2926dd elementor-widget elementor-widget-text-editor\" data-id=\"d2926dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Les pi\u00e8ces se concentrent sur la fa\u00e7on dont les Premi\u00e8res Nations ont influenc\u00e9 notre histoire, s&#8217;harmonisent parfaitement avec le nouvel accent mis sur les questions autochtones \u00e0 l&#8217;\u00e9cole et dans la soci\u00e9t\u00e9 canadienne en g\u00e9n\u00e9ral\u2026. <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-640addb elementor-widget elementor-widget-toggle\" data-id=\"640addb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1041\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1041\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1041\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1041\"><p>\u00abJe suis attrist\u00e9 de lire que la production Canada Roars Spring n&#8217;aura pas lieu cette ann\u00e9e. Ce programme sur l\u2019histoire du Canada a offert aux \u00e9tudiants un r\u00e9sum\u00e9 tr\u00e8s unique et inspirant du pass\u00e9 du Canada. Raconter l&#8217;histoire avec des acteurs, de la danse et de la musique a insuffl\u00e9 un sentiment de fiert\u00e9 dans l&#8217;\u00e9dification de notre nation. Le contenu couvrait tr\u00e8s bien le programme des 7e et 8e ann\u00e9es et a motiv\u00e9 les \u00e9l\u00e8ves \u00e0 travailler dur dans l&#8217;unit\u00e9 d&#8217;histoire dans l&#8217;espoir de gagner le privil\u00e8ge d&#8217;assister \u00e0 la production. Les pi\u00e8ces se concentrent sur la fa\u00e7on dont les Premi\u00e8res Nations ont influenc\u00e9 notre histoire, s&#8217;harmonisent parfaitement avec le nouvel accent mis sur les questions autochtones \u00e0 l&#8217;\u00e9cole et dans la soci\u00e9t\u00e9 canadienne en g\u00e9n\u00e9ral.<\/p>\n<p><br \/>J&#8217;esp\u00e8re que des plans pourront \u00eatre faits pour que le spectacle soit pr\u00e9sent\u00e9 dans un proche avenir. En un peu plus de 2 heures, l&#8217;\u00e9mission a fait revivre l&#8217;histoire de mes \u00e9l\u00e8ves, ce que le manuel et les vid\u00e9os \u00e9taient rarement capables de faire en 10 semaines de cours! \u00bbPaul Graham, \u00c9cole publique de Glashan \/ 8e ann\u00e9e<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce3a68c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ce3a68c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2d083f1\" data-id=\"2d083f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbad5e5 elementor-widget elementor-widget-text-editor\" data-id=\"cbad5e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Nous ne pouvons pas sous-estimer l&#8217;importance des arts dans la vie de nos \u00e9tudiants\u2026. <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-158589e elementor-widget elementor-widget-toggle\" data-id=\"158589e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2251\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2251\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2251\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2251\"><p>\u00abJe suis enseignant \u00e0 la Connaught Public School et j&#8217;enseigne \u00e0 un groupe d&#8217;\u00e9l\u00e8ves ayant un retard de d\u00e9veloppement dans un milieu semi-int\u00e9gr\u00e9.<\/p>\n<p>Nous avons \u00e9t\u00e9 extr\u00eamement chanceux d&#8217;avoir pu participer au salon Canada Roars. C&#8217;est une fa\u00e7on unique de raconter l&#8217;histoire du Canada. Cela a vraiment donn\u00e9 vie \u00e0 l&#8217;histoire de mes \u00e9tudiants.<\/p>\n<p>Non seulement ils ont pu voir la progression de la musique, mais ils ont \u00e9galement rencontr\u00e9 les interpr\u00e8tes qui sont rest\u00e9s en costume et en personnage pour que leurs enfants puissent interagir avec eux \u00e0 titre personnel, participer \u00e0 la musique et \u00e0 la danse, poser des questions, d\u00e9couvrez la culture et les artefacts d&#8217;hier. Les artistes \u00e9taient gentils et patients et tr\u00e8s enthousiastes \u00e0 l&#8217;id\u00e9e de partager leurs connaissances et leurs comp\u00e9tences.<\/p>\n<p>Ce programme est important car il montre aux \u00e9tudiants de tous horizons l&#8217;histoire du Canada, sa musique et sa culture. Nous ne pouvons sous-estimer l&#8217;importance des arts dans la vie de nos \u00e9tudiants. Cela nous donne du sens et de la profondeur et une plus grande appr\u00e9ciation et implication dans notre histoire \u00e0 mesure qu&#8217;elle prend vie.<\/p>\n<p>Merci d\u2019avoir financ\u00e9 ce programme et j\u2019estime qu\u2019il doit se poursuivre \u00e0 l\u2019avenir afin que, ann\u00e9e apr\u00e8s ann\u00e9e, les \u00e9tudiants puissent vivre l\u2019\u00e9merveillement de l\u2019histoire de la musique et de la danse au Canada.<\/p>\n<p>Anne-Marie de Souza, \u00c9cole publique Connaught<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-36d103d\" data-id=\"36d103d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9451299 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9451299\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c47a3a\" data-id=\"1c47a3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5a7625 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a5a7625\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avis sur le tourisme<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-183e554 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"183e554\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;2.5&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpolyline points=&#039;0,18 12,6 24,18 &#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5152c80 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5152c80\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-109ef41\" data-id=\"109ef41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4d1bb4 elementor-widget elementor-widget-text-editor\" data-id=\"e4d1bb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> C&#8217;\u00e9tait amusant, \u00e9motionnel, professionnel et patriotique\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ddd771 elementor-widget elementor-widget-toggle\" data-id=\"7ddd771\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1311\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1311\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1311\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1311\"><p>\u00abJ&#8217;ai \u00e9t\u00e9 submerg\u00e9 par la repr\u00e9sentation de A Musical Taste of Our Canadian Heritage. C&#8217;\u00e9tait amusant, \u00e9motionnel, professionnel et patriotique. Je le recommande vivement aux Canadiens de tout \u00e2ge. Bravo Deborah Davis! \u00bbJim Watson<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b167bc\" data-id=\"7b167bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e43d29 elementor-widget elementor-widget-text-editor\" data-id=\"4e43d29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Le spectacle pla\u00eet \u00e0 tout le monde ind\u00e9pendamment de la langue ou de l&#8217;\u00e2ge, et est un reflet musicalement divertissant et puissamment culturel de l&#8217;histoire et de la beaut\u00e9 de notre maison et de notre pays natal\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b74149 elementor-widget elementor-widget-toggle\" data-id=\"7b74149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1291\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1291\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1291\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1291\"><p>\u00abUn go\u00fbt musical de notre patrimoine canadien \/ Notre patrimoinecanadien, uneodyss\u00e9e musicale\u00bb est fortement recommand\u00e9 comme production id\u00e9ale pour mettre en valeur le Canada\u2026 nous recommandons cette production comme l&#8217;une des meilleures que le Canada a \u00e0 offrir\u2026 Le spectacle pla\u00eet \u00e0 tous, peu importe la langue ou l&#8217;\u00e2ge, et est un reflet musicalement divertissant et profond\u00e9ment culturel de l&#8217;histoire et de la beaut\u00e9 de notre maison et de notre terre natale. \u00bbGlenn Duncan, Tourisme &#8211; Ottawa &#8211; Tourisme<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de2061c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"de2061c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bba7858\" data-id=\"bba7858\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-441fa84 elementor-widget elementor-widget-text-editor\" data-id=\"441fa84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Il rassemble plus de 50 interpr\u00e8tes, 100 morceaux de musique et authentiques insignes et costumes\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6f49c5 elementor-widget elementor-widget-toggle\" data-id=\"d6f49c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2251\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2251\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2251\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2251\"><p>L\u2019\u00e9mission \u00e0 succ\u00e8s de Deborah Davis: Un go\u00fbt musical de notre patrimoine canadien \/ Notre patrimoinecanadien, uneodyss\u00e9e musicale est un public incroyable depuis douze ans. Il r\u00e9unit plus de 50 interpr\u00e8tes, 100 morceaux de musique et des insignes et costumes authentiques dans une odyss\u00e9e de 90 minutes de musique, de culture et d&#8217;histoire canadiennes. D&#8217;apr\u00e8s ma propre exp\u00e9rience, ce n&#8217;est pas une production que vous pouvez simplement vous asseoir et regarder passivement. Il est trop \u00e9mouvant et \u00e9difiant de ne pas engager le public \u00e0 un niveau personnel. Deborah a cr\u00e9\u00e9 quelque chose de remarquable et de remarquable. C&#8217;est un vrai talent. \u00bbL&#8217;hon. John P. Manley, P.C, OC, Conseil canadien des chefs d&#8217;entreprise<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-92a0ca0\" data-id=\"92a0ca0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dae1033 elementor-widget elementor-widget-text-editor\" data-id=\"dae1033\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Une superbe combinaison d&#8217;\u00e9ducation et de divertissement\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8041879 elementor-widget elementor-widget-toggle\" data-id=\"8041879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1341\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1341\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1341\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1341\"><p>\u201d\u2026 L&#8217;Odyssey Showcase est une superbe combinaison d&#8217;\u00e9ducation et de divertissement. C&#8217;\u00e9tait tr\u00e8s amusant de d\u00e9couvrir les moments forts de la musique canadienne au fil des ans de cette mani\u00e8re novatrice. Deborah Davis et sa distribution sont des interpr\u00e8tes terriblement talentueux et \u00e9nergiques. J&#8217;ai ador\u00e9 !!<\/p><p>Julie Jacobson (\u00e9pouse de l&#8217;ancien ambassadeur am\u00e9ricain David Jacobson)<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38fb0be elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"38fb0be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9fd5fd6\" data-id=\"9fd5fd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02d7a34 elementor-widget elementor-widget-text-editor\" data-id=\"02d7a34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Incroyable, excitant et envo\u00fbtant! &#8230;. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d99bba elementor-widget elementor-widget-toggle\" data-id=\"4d99bba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8131\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8131\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8131\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8131\"><p>\u201cIncroyable, excitant et envo\u00fbtant! \u2026 S\u00fbr d&#8217;impressionner et de ravir quiconque a la chance de pouvoir le voir! Nous allions encore et encore, cela nous laissait juste en vouloir plus alors que nous dansions &#8220;<\/p><p>Joanne Watts, Perspectives Eduscho Ltd.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-343eb2f\" data-id=\"343eb2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecaca72 elementor-widget elementor-widget-text-editor\" data-id=\"ecaca72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Non seulement il est amusant pour les jeunes (et pas si jeunes), mais peut aussi leur en apprendre beaucoup sur la langue et la culture\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24ff19f elementor-widget elementor-widget-toggle\" data-id=\"24ff19f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3871\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3871\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3871\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3871\"><p>\u00abQuel plaisir d&#8217;assister \u00e0 votre spectacle du 1er juin au Mus\u00e9e des civilisations!<br \/>Ma femme et moi avons beaucoup appr\u00e9ci\u00e9, et nous avions avec nous de vieux amis d&#8217;\u00c9cosse qui n&#8217;\u00e9taient jamais all\u00e9s au Canada auparavant &#8230; leur commentaire apr\u00e8s le spectacle \u00e9tait qu&#8217;ils aimaient le Canada &#8230; Permettez-moi aussi de dire, du point de vue de quelqu&#8217;un qui a d\u00e9pens\u00e9 son carri\u00e8re dans le domaine des langues officielles, que votre \u00e9mission est un moyen tr\u00e8s utile de convaincre les Canadiens, et d\u2019autres, de la valeur de l\u2019apprentissage des langues secondes. Il offre non seulement du plaisir aux jeunes (et pas si jeunes), mais peut \u00e9galement leur en apprendre beaucoup sur la langue et la culture. F\u00e9licitations et continuez le beau travail. \u00bbCharles Barker<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17674a8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"17674a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-50b21d5\" data-id=\"50b21d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4f3450 elementor-widget elementor-widget-text-editor\" data-id=\"c4f3450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Le point culminant de notre voyage d&#8217;une semaine \u00e0 Ottawa! &#8230;. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82f3422 elementor-widget elementor-widget-toggle\" data-id=\"82f3422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1371\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1371\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1371\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1371\"><p>\u00abUn avant-go\u00fbt musical de notre patrimoine canadien a \u00e9t\u00e9 le point culminant de notre voyage d&#8217;une semaine \u00e0 Ottawa! Ne manquez pas cette extravagance musicale et de danse merveilleuse et inspirante! \u00bbJon et Sherry Mahoney<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b5232fe\" data-id=\"b5232fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c11f4be elementor-widget elementor-widget-text-editor\" data-id=\"c11f4be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Il s&#8217;agit d&#8217;une production qui devrait \u00eatre vue par tous les Canadiens (et le monde) <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-692fc83 elementor-widget elementor-widget-toggle\" data-id=\"692fc83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1101\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1101\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1101\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1101\"><p>\u00ab\u2026 Depuis plusieurs ann\u00e9es, nous sommes conscients de la cr\u00e9ativit\u00e9, de la vitalit\u00e9, de la vision, de l&#8217;\u00e9nergie, de l&#8217;engagement et de l&#8217;art de Deborah Davis. (Poup\u00e9es en satin et un go\u00fbt musical de notre patrimoine canadien), Tout le monde r\u00eave de r\u00eaves, mais la diff\u00e9rence avec cette femme dynamique est qu&#8217;elle est particuli\u00e8rement capable de r\u00e9aliser ses r\u00eaves .. Cela n&#8217;est d\u00e9montr\u00e9 nulle part plus qu&#8217;avec Un go\u00fbt musical de notre Patrimoine canadien. Presque \u00e0 elle seule, elle a donn\u00e9 vie \u00e0 cette production impressionnante avec un budget limit\u00e9.<\/p><p>Nous nous souvenons bien d&#8217;avoir assist\u00e9 \u00e0 un spectacle public absorb\u00e9 et captiv\u00e9, tout comme le public entier, jeunes et vieux, car l&#8217;histoire du Canada \u00e9tait \u00e9troitement li\u00e9e aux sons distinctifs de la musique canadienne. C\u2019\u00e9tait vraiment une performance virtuose. Cela augmentait l\u2019appr\u00e9ciation du caract\u00e8re distinctif de la musique canadienne.<\/p><p>Quel concept intelligent et attrayant. Il s&#8217;agit d&#8217;une production que tous les Canadiens devraient voir pour rehausser leur fiert\u00e9 \u00e0 l&#8217;\u00e9gard de notre pays. Au-del\u00e0 de cela, les r\u00e9sidents de pays \u00e0 l&#8217;ext\u00e9rieur du Canada en apprendront davantage sur notre patrimoine color\u00e9 &#8211; cela aura un effet profond sur le tourisme. Plus nous y pensons, plus nous sommes convaincus que cette production pourrait devenir un incontournable de l\u2019\u00e9t\u00e9 dans la capitale de notre pays, attirant les Canadiens et les non-Canadiens, tout comme Anne of Green Gable le fait \u00e0 l\u2019\u00cele-du-Prince-\u00c9douard. \u2026 En tant que musiciens, chefs de ch\u0153ur, organisateurs de festivals de musique et gens d&#8217;affaires, nous appuyons sans r\u00e9serve Deborah Davis\u2026 Franchement, nous pensons aussi que cela a du bon sens pour Ottawa et l&#8217;Ontario!\u2026 .C&#8217;est une production qui devrait \u00eatre vue par tous les Canadiens (et le monde) pour rehausser leur fiert\u00e9 envers notre pays. Vraiment, une performance virtuose qui aura un effet profond sur le public. \u00bbLois et Donald Harper<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-070e7c6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"070e7c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d473c2\" data-id=\"5d473c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d01f871 elementor-widget elementor-widget-text-editor\" data-id=\"d01f871\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Pendentif tout le spectacle j\u2019ai ressenti une telle fiert\u00e9 envers mon pays\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9582a23 elementor-widget elementor-widget-toggle\" data-id=\"9582a23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1561\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1561\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1561\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1561\"><p><em>\u00a0<\/em>\u00ab\u00a0...Lorsque j\u2019\u00e9tais enfant, je m\u2019ennuyais du cours d\u2019histoire...et je sais que je n\u2019\u00e9tais pas la seule. Plus maintenant. Pendant tout le spectacle, j\u2019ai ressenti une telle fiert\u00e9 envers mon pays, tout en apprenant son histoire \u00e0 travers les nombreuses sc\u00e8nes historiques...Des Premi\u00e8res Nations et du peuple Inuit, en passant par le Qu\u00e9b\u00e9cois, le Fran\u00e7ais, les Celtes, les Acadiens...et tant d\u2019autres cultures et styles de musique, j\u2019ai d\u00e9couvert comme jamais auparavant, les plus importants \u00e9v\u00e9nements historiques pr\u00e9sent\u00e9s au moyen de chansons, de danses et de courtes pi\u00e8ces de th\u00e9\u00e2tre. Je n\u2019oublierai pas de sit\u020ft ces chapitres de l\u2019Histoire du Canada...parce que je me suis amus\u00e9e en apprenant...Pas une seule longueur durant tout le spectacle, un vrai tour de force! \u00bb<\/p><p><strong>Th\u00e9r\u00e8se Gauthier \/ L'Honorable Tommy Banks S\u00e9nateur (Alberta)<\/strong><\/p><h3><strong>\u00a0<\/strong><\/h3><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a196d5c\" data-id=\"a196d5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37b30c0 elementor-widget elementor-widget-text-editor\" data-id=\"37b30c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Il me reste un immense sentiment de fiert\u00e9 d&#8217;\u00eatre Canadien\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcdf349 elementor-widget elementor-widget-toggle\" data-id=\"dcdf349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2311\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2311\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2311\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2311\"><p>\u00abJe suis all\u00e9 voir Un avant-go\u00fbt musical de notre patrimoine canadien trois fois maintenant\u2026 Ce qui m&#8217;\u00e9tonne, c&#8217;est le nombre de chansons formidables qui sont canadiennes\u2026 Chaque fois que je regarde l&#8217;\u00e9mission, je me retrouve avec un immense sentiment de fiert\u00e9 d&#8217;\u00eatre un Canadien et mes mains me font mal en applaudissant avec la musique et en applaudissant les performances. J\u2019ai la conviction sinc\u00e8re et sinc\u00e8re que chaque Canadien et chaque visiteur de la capitale de notre pays devrait se rendre service et assister \u00e0 ce spectacle incroyable et \u00e9difiant sur le plan spirituel. Vous ne serez pas d\u00e9\u00e7u! \u00bbPeter Ventura<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75e4504 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"75e4504\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dde9d8f\" data-id=\"dde9d8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-309d473 elementor-widget elementor-widget-text-editor\" data-id=\"309d473\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> A favoris\u00e9 un plus grand sentiment de fiert\u00e9 et d&#8217;identit\u00e9 canadienne pour notre communaut\u00e9 autochtone\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad47488 elementor-widget elementor-widget-toggle\" data-id=\"ad47488\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1811\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1811\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1811\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1811\"><p>\u00abNous appr\u00e9cions le respect et la compr\u00e9hension que votre production d\u00e9montre sur les contributions uniques des premiers peuples \u00e0 la musique et \u00e0 l&#8217;histoire du Canada. Nous croyons fermement que la participation \u00e0 cette production a contribu\u00e9 \u00e0 cr\u00e9er une meilleure compr\u00e9hension des premi\u00e8res personnes pour le grand public. De plus, cela a favoris\u00e9 un plus grand sentiment de fiert\u00e9 et d&#8217;identit\u00e9 canadienne pour notre communaut\u00e9 autochtone\u2026 Professionnel et superbe.<\/p><p>Trina Mather Simard, Turtle Island: tourisme<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-69bc0fe\" data-id=\"69bc0fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e69c884 elementor-widget elementor-widget-text-editor\" data-id=\"e69c884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> J&#8217;ai ador\u00e9 entendre notre histoire\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b23f3a elementor-widget elementor-widget-toggle\" data-id=\"5b23f3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9551\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9551\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9551\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9551\"><p>\u00abJ&#8217;ai ador\u00e9 entendre notre histoire. Ce n&#8217;est pas tous les jours que vous pouvez entendre des chants de gorge inuits, des violons acadiens et de la musique folklorique canadienne en un seul endroit. C&#8217;\u00e9tait incroyable. \u00bbSarah Mahoney<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75154cb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"75154cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2d8c086\" data-id=\"2d8c086\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bcb704 elementor-widget elementor-widget-text-editor\" data-id=\"7bcb704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Nous fait prendre conscience du r\u00f4le que l&#8217;expression culturelle a jou\u00e9 et continue de jouer dans le renforcement des liens de coh\u00e9sion sociale dans ce pays\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43c5362 elementor-widget elementor-widget-toggle\" data-id=\"43c5362\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7101\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7101\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7101\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7101\"><p>\u00ab\u2026 \u00c0 mon avis, c\u2019est une \u0153uvre pionni\u00e8re qui, en nous faisant go\u00fbter au riche patrimoine musical du Canada, nous fait tous prendre conscience du r\u00f4le que l\u2019expression culturelle a jou\u00e9 et continue de jouer dans le renforcement des liens de coh\u00e9sion sociale dans ce pays. Nos lois et notre Parlement ne forment que la moiti\u00e9 de l&#8217;\u00e9quation, notre expression culturelle, dont la musique est une partie importante, forme l&#8217;autre.<\/p><p>Dr Paul Benoit, PhD, Bureau du commerce international du ministre du Commerce international et du ministre de la porte d&#8217;entr\u00e9e du Pacifique et des Olympiques de Vancouver-Whistler<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dafadfc\" data-id=\"dafadfc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76044fd elementor-widget elementor-widget-text-editor\" data-id=\"76044fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Quelle merveilleuse fa\u00e7on de d\u00e9couvrir l&#8217;histoire canadienne\u2026. <\/b> <\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1083ef elementor-widget elementor-widget-toggle\" data-id=\"d1083ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2191\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2191\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2191\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2191\"><p>\u00abApr\u00e8s avoir pass\u00e9 trois jours pleins d&#8217;action \u00e0 Ottawa, les \u00e9l\u00e8ves consid\u00e8rent toujours\u00ab Odyssey Showcase \/ \u00abA Musical Taste of Our Canadian Heritage \/ Notre patrimoinecanadien, uneodyss\u00e9e musicale\u00bb \u00bbcomme leur \u00e9v\u00e9nement pr\u00e9f\u00e9r\u00e9. Quelle merveilleuse fa\u00e7on de VIVRE r\u00e9ellement l&#8217;histoire du Canada. Enseigner par la musique et le th\u00e9\u00e2tre est un m\u00e9dia rarement utilis\u00e9 dans notre syst\u00e8me \u00e9ducatif. Pour les \u00e9tudiants qui ont des d\u00e9fis comme le mien, le spectacle leur a enseign\u00e9 le Canada et leur patrimoine d&#8217;une mani\u00e8re dynamique et impressionnante. Au nom des \u00e9l\u00e8ves de l&#8217;\u00e9cole secondaire Joliette\u2026 Merci pour les souvenirs! Au plaisir de vous revoir\u2026 Veuillez nous tenir au courant. \u00bb<\/p><p>Sharon St Maurice, \u00c9cole secondaire Joliette<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-810f9c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"810f9c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33a00a8\" data-id=\"33a00a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63ededa elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"63ededa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Examens p\u00e9dagogiques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2800aef elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2800aef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;2.5&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpolyline points=&#039;0,18 12,6 24,18 &#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d567ce elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8d567ce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-85ef75b\" data-id=\"85ef75b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd7fe3e elementor-widget elementor-widget-text-editor\" data-id=\"fd7fe3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Il touche l&#8217;\u00e2me et \u00e9l\u00e8ve les sens\u2026. <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa96cf0 elementor-widget elementor-widget-toggle\" data-id=\"fa96cf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2621\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2621\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2621\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2621\"><p>\u00abLa puissante production bilingue de Deborah Davis, savamment recherch\u00e9e, intitul\u00e9e\u00ab A Musical Taste of Our Canadian Heritage \/ Notre patrimoinecanadien, uneodyss\u00e9e musicale \u00bbest une performance collaborative impr\u00e9gn\u00e9e de musique, de danse, de chanson et de r\u00e9cit historique refl\u00e9tant l&#8217;exp\u00e9rience canadienne, pass\u00e9e et pr\u00e9sente. Cet outil d\u2019enseignement interactif de 90 minutes non seulement suscite un int\u00e9r\u00eat pour la musique et l\u2019histoire de notre pays, mais cultive chez le public un sentiment de fiert\u00e9 nationale, tout en cr\u00e9ant potentiellement une toute nouvelle g\u00e9n\u00e9ration de spectateurs. Il touche l&#8217;\u00e2me et \u00e9l\u00e8ve les sens, quel que soit l&#8217;\u00e2ge du public. C&#8217;est g\u00e9nial! Vous ne serez pas d\u00e9\u00e7u!&#8221;<\/p>\n<p>Donna Kenny, \u00c9cole interm\u00e9diaire Cedarview<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-15e5e7f\" data-id=\"15e5e7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07a0fad elementor-widget elementor-widget-text-editor\" data-id=\"07a0fad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Vous pourriez ressentir l&#8217;\u00e9nergie et l&#8217;excitation de l&#8217;histoire du Canada\u2026. <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70ca54c elementor-widget elementor-widget-toggle\" data-id=\"70ca54c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1181\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1181\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1181\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1181\"><p>\u00ab\u2026. Cette production \u00e9tait incroyable !!! C\u2019\u00e9tait passionnant tout au long\u2026 Une exp\u00e9rience palpitante, les costumes \u00e9taient authentiques, les interpr\u00e8tes engageants\u2026 On pouvait ressentir l\u2019\u00e9nergie et l\u2019excitation de l\u2019histoire du Canada\u2026. une occasion vraiment unique de se connecter avec la grande histoire de la chanson et de la danse canadiennes. \u00bbMelanie<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c388932 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c388932\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f724671\" data-id=\"f724671\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-618d10a elementor-widget elementor-widget-text-editor\" data-id=\"618d10a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> L&#8217;\u00e9mission fascine les \u00e9l\u00e8ves du d\u00e9but \u00e0 la fin\u2026 <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65e967e elementor-widget elementor-widget-toggle\" data-id=\"65e967e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1061\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1061\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1061\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1061\"><p>\u00abUn go\u00fbt musical est extr\u00eamement pr\u00e9cieux d&#8217;un point de vue \u00e9ducatif, car il change la fa\u00e7on dont les \u00e9l\u00e8ves regardent l&#8217;histoire et les expose aux arts et aux \u00e9tudes sociales d&#8217;une mani\u00e8re qu&#8217;ils n&#8217;auraient jamais pu vivre autrement. Le spectacle fascine les \u00e9tudiants du d\u00e9but \u00e0 la fin et les emm\u00e8ne dans un voyage \u00e0 travers l&#8217;\u00e9volution de notre pays et de ses habitants. Les liens entre la musique, la danse, les v\u00eatements, les gens et le d\u00e9veloppement physique de la terre sont vifs et fournissent des liens qui ne peuvent pas \u00eatre \u00e9tablis par le biais de manuels, de DVD et de CD. A Musical Taste est une production multidisciplinaire qui regroupe plusieurs des \u00abgrandes id\u00e9es\u00bb pr\u00e9sent\u00e9es dans les documents Arts and Social Studies \/ History \/ Geography du curriculum de l&#8217;Ontario, et elle a un impact \u00e9norme sur les \u00e9tudiants\u2026<\/p>\n<p>Le manuel de l&#8217;enseignant qui l&#8217;accompagne est un atout car il propose de nombreuses activit\u00e9s cr\u00e9atives qui aident les enseignants \u00e0 prolonger l&#8217;excitation de la production dans la salle de classe pendant des semaines par la suite, tout en augmentant les connaissances, l&#8217;appr\u00e9ciation et la participation des \u00e9l\u00e8ves. Le manuel fournit les informations de base n\u00e9cessaires aux enseignants, et les activit\u00e9s permettent une int\u00e9gration avec le document du curriculum des arts du langage de l&#8217;Ontario et les comp\u00e9tences technologiques. C&#8217;est vraiment une fa\u00e7on pratique et novatrice d&#8217;enseigner aux \u00e9l\u00e8ves leur \u00abpays d&#8217;origine et leur pays d&#8217;origine\u00bb tout en int\u00e9grant le contenu de base, et \u00e0 mon avis, cela devrait \u00eatre une composante obligatoire de l&#8217;\u00e9ducation de tous les \u00e9tudiants canadiens. Au nom de tous les enseignants, je vous remercie pour ce merveilleux programme.<\/p>\n<p>Naomi Ventura, \u00e9cole publique principale Hazel McCallion<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ccf5259\" data-id=\"ccf5259\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31accb3 elementor-widget elementor-widget-text-editor\" data-id=\"31accb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> La production et le manuel ne sont rien de moins que g\u00e9niaux\u2026. <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d490c45 elementor-widget elementor-widget-toggle\" data-id=\"d490c45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2221\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2221\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2221\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2221\"><p>\u00abLa production et le manuel ne sont rien de moins que brillants. Ils sont tout autant une histoire du Canada qu&#8217;une histoire de divers genres musicaux. Il s&#8217;agit d&#8217;une visite de notre vaste territoire avec un regard sociologique sur nos provinces et territoires. Je n&#8217;h\u00e9siterai absolument pas \u00e0 utiliser des parties de ce manuel dans mes cours coll\u00e9giaux-universitaires et je n&#8217;h\u00e9siterai pas non plus \u00e0 recommander la production et le manuel \u00e0 tous les \u00e9ducateurs. C&#8217;est une excellente contribution \u00e0 l&#8217;apprentissage! \u00bb<\/p>\n<p>Professeur Gerry Cammy, Heritage College, CFRA<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b8c275 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1b8c275\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-22dbdcb\" data-id=\"22dbdcb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7620869 elementor-widget elementor-widget-text-editor\" data-id=\"7620869\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> J&#8217;ai vu des \u00e9tudiants qui, de toute \u00e9vidence, voyaient l&#8217;histoire du Canada sous un nouveau jour <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f330694 elementor-widget elementor-widget-toggle\" data-id=\"f330694\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2551\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2551\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2551\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2551\"><p>\u00abLa production met non seulement l&#8217;accent sur le r\u00f4le important de la musique dans l&#8217;histoire canadienne, mais utilise \u00e9galement la musique comme point d&#8217;entr\u00e9e pour des discussions connexes sur l&#8217;ensemble des changements sociaux, \u00e9conomiques, culturels et politiques. Cette approche est conforme \u00e0 l&#8217;orientation actuelle de l&#8217;enseignement et de la recherche interdisciplinaires en \u00e9ducation ainsi qu&#8217;aux efforts visant \u00e0 relier les \u00e9coles et la communaut\u00e9 dans son ensemble.<\/p>\n<p>\u00ab\u2026 De mani\u00e8re cr\u00e9ative et convaincante, Deborah Davis et ses coll\u00e8gues sont \u00e0 l\u2019avant-garde de ces efforts novateurs pour soutenir l\u2019\u00e9tude du pass\u00e9 du Canada. Ils ont montr\u00e9 comment la musique peut stimuler, inspirer et informer les \u00e9l\u00e8ves sur les principales transformations sociales et culturelles dans la construction du Canada moderne. Au cours des derni\u00e8res ann\u00e9es, j\u2019ai eu le plaisir d\u2019exp\u00e9rimenter de premi\u00e8re main l\u2019enthousiasme et l\u2019engagement des \u00e9tudiants qui \u00abgo\u00fbtent\u00bb au patrimoine musical canadien, et mon enthousiasme pour cette approche est le r\u00e9sultat direct de cette exp\u00e9rience. J&#8217;ai vu des \u00e9tudiants qui, de toute \u00e9vidence, voyaient l&#8217;histoire du Canada sous un nouveau jour. Ils \u00e9taient, en effet, en train de devenir des apprenants actifs qui se connectaient avec le pass\u00e9 par leur appr\u00e9ciation et leur \u00e9merveillement devant les sons et les images de notre patrimoine musical\u2026 \u00bb<\/p>\n<p>Professeur Chad Gaffield, Universit\u00e9 d&#8217;Ottawa<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7013c1e\" data-id=\"7013c1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c59b6e8 elementor-widget elementor-widget-text-editor\" data-id=\"c59b6e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Fascinant, attrayant et pertinent pour la compr\u00e9hension de l&#8217;histoire canadienne. <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c6817f elementor-widget elementor-widget-toggle\" data-id=\"4c6817f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8011\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8011\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8011\"><p>\u00abCe n&#8217;est qu&#8217;un petit mot pour vous faire savoir \u00e0 quel point j&#8217;ai aim\u00e9 votre production de Un go\u00fbt musical de notre patrimoine canadien que j&#8217;ai eu le plaisir de voir \u00e0 Ottawa en mai dernier. Je l&#8217;ai trouv\u00e9 fascinant, attrayant et pertinent pour la compr\u00e9hension de l&#8217;histoire canadienne. Je suis s\u00fbr que les \u00e9l\u00e8ves adoreront le voir et que les enseignants en feront certainement la promotion. \u00bb<\/p>\n<p>Canjita Gomes-Fernandes, PhD, Commission scolaire English-Montr\u00e9al<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b97aaf2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b97aaf2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1de2722\" data-id=\"1de2722\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b5d135 elementor-widget elementor-widget-text-editor\" data-id=\"0b5d135\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-column\">\n<p class=\"has-black-color has-text-color\"><\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c882cd elementor-widget elementor-widget-text-editor\" data-id=\"7c882cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> Nous avons tout de suite \u00e9t\u00e9 impressionn\u00e9s par l&#8217;originalit\u00e9 de ce concept <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-382c049 elementor-widget elementor-widget-toggle\" data-id=\"382c049\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5891\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5891\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5891\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5891\"><p>La musique est en effet depuis longtemps reconnue par les \u00e9ducateurs comme le moyen d&#8217;enseignement le plus efficace, mais elle n&#8217;a jamais \u00e9t\u00e9 appliqu\u00e9e \u00e0 l&#8217;histoire \u00e0 une telle \u00e9chelle. Comme la GRC a jou\u00e9 un r\u00f4le crucial dans le d\u00e9veloppement du Canada, en particulier dans \u00e0 la recherche de nouvelles fa\u00e7ons de promouvoir cet aspect souvent oubli\u00e9 de notre organisation. En collaboration avec Mme Davis et son \u00e9quipe, nous avons identifi\u00e9 plusieurs morceaux de musique de la GRC qui nous permettraient de promouvoir le r\u00f4le que notre institution a jou\u00e9 dans l&#8217;\u00e9dification de la nation. La Section historique de la GRC a fourni des images et des informations historiques que Mme Davis a combin\u00e9es avec de la musique d&#8217;\u00e9poque. Le r\u00e9sultat \u00e9tait une repr\u00e9sentation tr\u00e8s \u00e9mouvante, mais historiquement exacte du r\u00f4le de la GRC \u00e0 la fin du 19e si\u00e8cle\u2026 Nous avons eu l&#8217;honneur d&#8217;assister \u00e0 la production et avons \u00e9t\u00e9 imm\u00e9diatement impressionn\u00e9s par le haut calibre de tous les interpr\u00e8tes et musiciens. Le produit final \u00e9tait un aper\u00e7u vivant et \u00e9mouvant de la riche histoire du Canada, du contact pr\u00e9-europ\u00e9en au 21e si\u00e8cle. \u00c0 en juger par la r\u00e9ponse du public, nous n\u2019\u00e9tions pas seuls dans notre sentiment. Nous croyons qu&#8217;un avant-go\u00fbt musical de notre patrimoine canadien est une entreprise extr\u00eamement utile qui inculquerait aux Canadiens une plus grande appr\u00e9ciation de notre patrimoine\u2026 \u00bb<\/p>\n<p>Sandy Ramos, Direction des partenariats strat\u00e9giques et du patrimoine de la GRC<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fb2f897\" data-id=\"fb2f897\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-449e890 elementor-widget elementor-widget-text-editor\" data-id=\"449e890\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"wp-block-column\">\n<p class = \"has-black-color has-text-color\"> <i class = \"fa fa-quote-left\" style = \"font-size: 25px;\" aria-hidden = \"true\"> <\/i> <b> La qualit\u00e9 du talent, la cr\u00e9ativit\u00e9 de la performance et la passion des interpr\u00e8tes \u00e9taient inspirantes\u2026. <\/b> <\/p>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db1586c elementor-widget elementor-widget-toggle\" data-id=\"db1586c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2291\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2291\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Rail Plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2291\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2291\"><p>\u00abTD Canada Trust fait partie de cette production depuis le d\u00e9but et nous sommes fiers de continuer notre soutien\u2026 J&#8217;ai eu le plaisir d&#8217;assister \u00e0 cette production au moins quatre fois et \u00e0 chaque fois j&#8217;\u00e9tais plus impressionn\u00e9\u2026 la qualit\u00e9 du talent, la cr\u00e9ativit\u00e9 de la performance et de la passion des interpr\u00e8tes \u00e9tait inspirante &#8230; c&#8217;\u00e9tait excellent, repr\u00e9sentant notre culture diversifi\u00e9e et mettant en valeur de nombreuses l\u00e9gendes canadiennes &#8230; la production m&#8217;a rendu fier &#8230; tout simplement, Wow!<\/p>\n<p>Cathy Jowsey, R\u00e9gion du Nord et de l&#8217;Est de l&#8217;Ontario TD Canada Trust<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Avis sur Odyssey Showcase Le don du jazz, le don de la culture, le don de la musique et le don d&#8217;une exp\u00e9rience live, partag\u00e9e par tous les \u00e2ges. Rail Plus Le don du jazz, le don de la culture, le don de la musique et le don d&rsquo;une exp\u00e9rience live, partag\u00e9e par tous les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":6238,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7482","page","type-page","status-publish","hentry","no-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En r\u00e9sum\u00e9 - Odyssey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseyshowcase.org\/fr\/a-propos-de-nous\/en-resume\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En r\u00e9sum\u00e9 - Odyssey\" \/>\n<meta property=\"og:description\" content=\"Avis sur Odyssey Showcase Le don du jazz, le don de la culture, le don de la musique et le don d&#8217;une exp\u00e9rience live, partag\u00e9e par tous les \u00e2ges. Rail Plus Le don du jazz, le don de la culture, le don de la musique et le don d&rsquo;une exp\u00e9rience live, partag\u00e9e par tous les [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseyshowcase.org\/fr\/a-propos-de-nous\/en-resume\/\" \/>\n<meta property=\"og:site_name\" content=\"Odyssey\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/canadaroars\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-02T11:13:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@canadaroars\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"71 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/odysseyshowcase.org\\\/a-propos-de-nous\\\/en-resume\\\/\",\"url\":\"https:\\\/\\\/odysseyshowcase.org\\\/a-propos-de-nous\\\/en-resume\\\/\",\"name\":\"En r\u00e9sum\u00e9 - Odyssey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/odysseyshowcase.org\\\/#website\"},\"datePublished\":\"2021-04-01T12:48:41+00:00\",\"dateModified\":\"2021-04-02T11:13:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/odysseyshowcase.org\\\/a-propos-de-nous\\\/en-resume\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/odysseyshowcase.org\\\/a-propos-de-nous\\\/en-resume\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/odysseyshowcase.org\\\/a-propos-de-nous\\\/en-resume\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/odysseyshowcase.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 propos de nous\",\"item\":\"https:\\\/\\\/odysseyshowcase.org\\\/a-propos-de-nous\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"En r\u00e9sum\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/odysseyshowcase.org\\\/#website\",\"url\":\"https:\\\/\\\/odysseyshowcase.org\\\/\",\"name\":\"Odyssey Showcase\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/odysseyshowcase.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/odysseyshowcase.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/odysseyshowcase.org\\\/#organization\",\"name\":\"Odyssey Showcase\",\"url\":\"https:\\\/\\\/odysseyshowcase.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/odysseyshowcase.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/odysseyshowcase.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/odyssey_showcase_website_logo.png\",\"contentUrl\":\"https:\\\/\\\/odysseyshowcase.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/odyssey_showcase_website_logo.png\",\"width\":537,\"height\":209,\"caption\":\"Odyssey Showcase\"},\"image\":{\"@id\":\"https:\\\/\\\/odysseyshowcase.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/canadaroars\",\"https:\\\/\\\/x.com\\\/canadaroars\",\"https:\\\/\\\/ca.linkedin.com\\\/in\\\/deborah-davis-10b69b1a\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/54278895@N05\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En r\u00e9sum\u00e9 - Odyssey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseyshowcase.org\/fr\/a-propos-de-nous\/en-resume\/","og_locale":"fr_CA","og_type":"article","og_title":"En r\u00e9sum\u00e9 - Odyssey","og_description":"Avis sur Odyssey Showcase Le don du jazz, le don de la culture, le don de la musique et le don d&#8217;une exp\u00e9rience live, partag\u00e9e par tous les \u00e2ges. Rail Plus Le don du jazz, le don de la culture, le don de la musique et le don d&rsquo;une exp\u00e9rience live, partag\u00e9e par tous les [&hellip;]","og_url":"https:\/\/odysseyshowcase.org\/fr\/a-propos-de-nous\/en-resume\/","og_site_name":"Odyssey","article_publisher":"https:\/\/www.facebook.com\/canadaroars","article_modified_time":"2021-04-02T11:13:05+00:00","twitter_card":"summary_large_image","twitter_site":"@canadaroars","twitter_misc":{"Est. reading time":"71 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseyshowcase.org\/a-propos-de-nous\/en-resume\/","url":"https:\/\/odysseyshowcase.org\/a-propos-de-nous\/en-resume\/","name":"En r\u00e9sum\u00e9 - Odyssey","isPartOf":{"@id":"https:\/\/odysseyshowcase.org\/#website"},"datePublished":"2021-04-01T12:48:41+00:00","dateModified":"2021-04-02T11:13:05+00:00","breadcrumb":{"@id":"https:\/\/odysseyshowcase.org\/a-propos-de-nous\/en-resume\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseyshowcase.org\/a-propos-de-nous\/en-resume\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/odysseyshowcase.org\/a-propos-de-nous\/en-resume\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseyshowcase.org\/"},{"@type":"ListItem","position":2,"name":"\u00c0 propos de nous","item":"https:\/\/odysseyshowcase.org\/a-propos-de-nous\/"},{"@type":"ListItem","position":3,"name":"En r\u00e9sum\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/odysseyshowcase.org\/#website","url":"https:\/\/odysseyshowcase.org\/","name":"Pr\u00e9sentoire de L'odyss\u00e9e","description":"","publisher":{"@id":"https:\/\/odysseyshowcase.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseyshowcase.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/odysseyshowcase.org\/#organization","name":"Pr\u00e9sentoire de L'odyss\u00e9e","url":"https:\/\/odysseyshowcase.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/odysseyshowcase.org\/#\/schema\/logo\/image\/","url":"https:\/\/odysseyshowcase.org\/wp-content\/uploads\/2021\/03\/odyssey_showcase_website_logo.png","contentUrl":"https:\/\/odysseyshowcase.org\/wp-content\/uploads\/2021\/03\/odyssey_showcase_website_logo.png","width":537,"height":209,"caption":"Odyssey Showcase"},"image":{"@id":"https:\/\/odysseyshowcase.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/canadaroars","https:\/\/x.com\/canadaroars","https:\/\/ca.linkedin.com\/in\/deborah-davis-10b69b1a","https:\/\/www.flickr.com\/photos\/54278895@N05\/"]}]}},"_links":{"self":[{"href":"https:\/\/odysseyshowcase.org\/fr\/wp-json\/wp\/v2\/pages\/7482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odysseyshowcase.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/odysseyshowcase.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/odysseyshowcase.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odysseyshowcase.org\/fr\/wp-json\/wp\/v2\/comments?post=7482"}],"version-history":[{"count":22,"href":"https:\/\/odysseyshowcase.org\/fr\/wp-json\/wp\/v2\/pages\/7482\/revisions"}],"predecessor-version":[{"id":7787,"href":"https:\/\/odysseyshowcase.org\/fr\/wp-json\/wp\/v2\/pages\/7482\/revisions\/7787"}],"up":[{"embeddable":true,"href":"https:\/\/odysseyshowcase.org\/fr\/wp-json\/wp\/v2\/pages\/6238"}],"wp:attachment":[{"href":"https:\/\/odysseyshowcase.org\/fr\/wp-json\/wp\/v2\/media?parent=7482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}